{"id":2828,"date":"2025-12-09T21:06:35","date_gmt":"2025-12-10T04:06:35","guid":{"rendered":"https:\/\/family.cplea.ca\/?post_type=article&#038;p=2828"},"modified":"2026-01-26T11:01:25","modified_gmt":"2026-01-26T18:01:25","slug":"se-rendre-a-la-cour-du-banc-du-roi","status":"publish","type":"article","link":"https:\/\/family.cplea.ca\/fr\/article\/se-rendre-a-la-cour-du-banc-du-roi\/","title":{"rendered":"Se rendre \u00e0 la Cour du Banc du Roi"},"content":{"rendered":"\n<div class=\"wp-block-group is-style-lead has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<p>La Cour du Banc du Roi peut traiter toutes les questions en droit de la famille, y compris le divorce, le partage des biens familiaux, la pension alimentaire pour enfants et pour conjoint ou partenaire, ainsi que le temps parental.<\/p>\n\n\n\n<p>Le processus pour les affaires familiales \u00e0 la Cour du Banc du Roi a chang\u00e9 le <strong>2er janvier 2026<\/strong>. Le nouveau processus s\u2019appelle le <strong>Family Focused Protocol (FFP)<\/strong>. Le FFP encourage les deux parties \u00e0 travailler ensemble pour r\u00e9gler toutes ou la plupart des questions, et vise \u00e0 r\u00e9duire le nombre de comparutions r\u00e9p\u00e9t\u00e9es devant le tribunal. Ce processus s\u2019applique \u00e0 la plupart des dossiers \u00e0 la Cour, m\u00eame si votre cause est en cours depuis plusieurs ann\u00e9es.<\/p>\n\n\n\n<p>La Cour du Banc du Roi a plus de r\u00e8gles et de frais que la Cour de justice de l\u2019Alberta. Vous n\u2019avez pas besoin d\u2019un avocat pour vous repr\u00e9senter \u00e0 la Cour du Banc du Roi. Par contre, un avocat peut rendre le processus plus facile pour vous.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-style-mobile-jumplinks is-style-sidebar ghostkit-d-none ghostkit-d-xl-none ghostkit-d-lg-none ghostkit-d-md-none ghostkit-d-sm-block has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading on-this-page\">Sur cette page<\/h2>\n<ul class=\"toc\"><\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:75%\">\n<div class=\"wp-block-group is-style-summary is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Besoin de savoir<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La Cour du Banc du Roi utilise diff\u00e9rents proc\u00e9dures pour traiter diff\u00e9rents types de probl\u00e8mes.<\/li>\n\n\n\n<li>La Cour a des proc\u00e9dures pr\u00e9cis pour les situations urgentes, les demandes sans comparution (desk applications) et certains autres types de dossiers.<\/li>\n\n\n\n<li>La plupart des questions en droit de la famille passent par la proc\u00e9dure familial normale, qui comprend cinq \u00e9tapes importantes.<\/li>\n\n\n\n<li>Dans la proc\u00e9dure familial normale, la Cour assigne un juge \u00e0 votre dossier. Ce juge vous aide \u00e0 faire avancer<\/li>\n<\/ul>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Pour commencer<\/h2>\n\n\n\n<p class=\"is-style-learn-the-basics\">Apprenez les bases <a href=\"https:\/\/family.cplea.ca\/fr\/article\/les-tribunaux-et-les-lois-de-la-famille\/\">des tribunaux de la famille et des lois<\/a> en Alberta avant de vous rendre \u00e0 la Cour du Banc du Roi.<\/p>\n\n\n\n<p>Ensuite, il y a quelques points importants \u00e0 conna\u00eetre, m\u00eame si ce n\u2019est pas votre premi\u00e8re fois devant ce tribunal.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Diff\u00e9rents proc\u00e9dures pour diff\u00e9rents probl\u00e8mes<\/h3>\n\n\n\n<p>Il existe diff\u00e9rents proc\u00e9dures \u00e0 la Cour du Banc du Roi pour traiter diff\u00e9rents types de probl\u00e8mes. Vous trouverez ci-dessous plus d\u2019information sur le moment d\u2019utiliser chaque proc\u00e9dure.<\/p>\n\n\n\n<div class=\"ghostkit-accordion ghostkit-accordion-4\">\n<div class=\"ghostkit-accordion-item\" data-accordion=\"accordion-demande-urgente\"><div class=\"ghostkit-accordion-item-heading\"><button type=\"button\" id=\"accordion-demande-urgente-button\" aria-expanded=\"false\" aria-controls=\"accordion-demande-urgente-content\"><span class=\"ghostkit-accordion-item-label\">Demande urgente<\/span><span class=\"ghostkit-accordion-item-collapse\"><svg class=\"ghostkit-svg-icon\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M9.21967 6.2197C9.51256 5.9268 9.98744 5.9268 10.2803 6.2197L15.5303 11.4697C15.8232 11.7626 15.8232 12.2374 15.5303 12.5303L10.2803 17.7803C9.98744 18.0732 9.51256 18.0732 9.21967 17.7803C8.92678 17.4874 8.92678 17.0126 9.21967 16.7197L13.9393 12L9.21967 7.2803C8.92678 6.9874 8.92678 6.5126 9.21967 6.2197Z\" fill=\"currentColor\"><\/path><\/svg><\/span><\/button><\/div><div id=\"accordion-demande-urgente-content\" class=\"ghostkit-accordion-item-content is-layout-flow wp-block-ghostkit-accordion-item-is-layout-flow\" role=\"region\" aria-labelledby=\"accordion-demande-urgente-button\">\n<p>Une demande urgente s\u2019applique aux situations qui ne peuvent pas attendre de passer par une proc\u00e9dure judiciaire normale.<\/p>\n\n\n\n<p>Vous pouvez demander au tribunal d\u2019utiliser une demande urgente dans les situations suivantes :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Il y a un risque de pr\u00e9judice ou de violence pour vous ou pour un enfant.<\/li>\n\n\n\n<li>Vous voulez avoir <a href=\"https:\/\/family.cplea.ca\/fr\/article\/quarrive-t-il-a-votre-maison\/\">la possession exclusive du domicile familial<\/a> parce qu\u2019il y a un risque de pr\u00e9judice ou de violence pour vous ou pour un enfant.<\/li>\n\n\n\n<li>Il y a un risque qu\u2019une personne emm\u00e8ne un enfant hors de l\u2019Alberta sans permission.<\/li>\n\n\n\n<li>Vous avez un probl\u00e8me li\u00e9 <a href=\"https:\/\/family.cplea.ca\/fr\/article\/etre-parent-ou-tuteur\/\">au temps parental ou aux contacts avec un enfant<\/a> qui ne peut pas attendre.<\/li>\n\n\n\n<li>Le tribunal doit examiner <a href=\"https:\/\/family.cplea.ca\/fr\/article\/que-faire-en-cas-de-violence-familiale\/\">une ordonnance de protection d\u2019urgence<\/a>.<\/li>\n<\/ul>\n\n\n\n<p>Pour en savoir plus sur la fa\u00e7on de faire une demande urgente, consultez <a href=\"https:\/\/www.albertacourts.ca\/kb\/court-operations-schedules\/urgent\">le site Web de la Cour du Banc du Roi<\/a> (en anglais seulement). Si le tribunal d\u00e9cide que votre probl\u00e8me n\u2019est pas urgent, vous devrez plut\u00f4t utiliser la proc\u00e9dure familial normale.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"ghostkit-accordion-item\" data-accordion=\"accordion-la-procedure-de-demande-sans-comparution\"><div class=\"ghostkit-accordion-item-heading\"><button type=\"button\" id=\"accordion-la-procedure-de-demande-sans-comparution-button\" aria-expanded=\"false\" aria-controls=\"accordion-la-procedure-de-demande-sans-comparution-content\"><span class=\"ghostkit-accordion-item-label\"><strong>La proc\u00e9dure de demande sans comparution<\/strong><\/span><span class=\"ghostkit-accordion-item-collapse\"><svg class=\"ghostkit-svg-icon\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M9.21967 6.2197C9.51256 5.9268 9.98744 5.9268 10.2803 6.2197L15.5303 11.4697C15.8232 11.7626 15.8232 12.2374 15.5303 12.5303L10.2803 17.7803C9.98744 18.0732 9.51256 18.0732 9.21967 17.7803C8.92678 17.4874 8.92678 17.0126 9.21967 16.7197L13.9393 12L9.21967 7.2803C8.92678 6.9874 8.92678 6.5126 9.21967 6.2197Z\" fill=\"currentColor\"><\/path><\/svg><\/span><\/button><\/div><div id=\"accordion-la-procedure-de-demande-sans-comparution-content\" class=\"ghostkit-accordion-item-content is-layout-flow wp-block-ghostkit-accordion-item-is-layout-flow\" role=\"region\" aria-labelledby=\"accordion-la-procedure-de-demande-sans-comparution-button\">\n<p>La proc\u00e9dure de demande sans comparution s\u2019agit d\u2019une d\u00e9marche par laquelle vous pr\u00e9sentez une demande d\u2019ordonnance judiciaire en d\u00e9posant vos documents au palais de justice afin qu\u2019un juge les examine de fa\u00e7on ind\u00e9pendante. Vous ne comparaissez pas devant le juge et ne lui adressez pas la parole. Le tribunal communique avec vous une fois que le juge a rendu sa d\u00e9cision, s\u2019il accorde l\u2019ordonnance, s\u2019il requiert des renseignements suppl\u00e9mentaires ou s\u2019il refuse de rendre l\u2019ordonnance demand\u00e9e.<br>Vous devez utiliser la proc\u00e9dure de demande sans comparution pour les situations suivantes :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/family.cplea.ca\/fr\/article\/rendre-une-ordonnance-par-consentement\/\">les ordonnances par consentement<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/family.cplea.ca\/fr\/article\/obtenir-un-divorce\/\">les divorces conjoints<\/a><\/li>\n\n\n\n<li>les demandes visant \u00e0 exempter ou reporter les quatre exigences obligatoires avant la cour<\/li>\n\n\n\n<li>les demandes pour rencontrer un avocat en r\u00e8glement des diff\u00e9rends (Resolution Counsel)<\/li>\n\n\n\n<li>les ordonnances concernant les r\u00e8gles et proc\u00e9dures du tribunal (par exemple, si vous avez besoin de la permission du tribunal pour d\u00e9poser un document apr\u00e8s la date limite)<\/li>\n\n\n\n<li>les demandes pour obliger l\u2019autre personne \u00e0 partager ses renseignements financiers avec vous<\/li>\n<\/ul>\n\n\n\n<p>Les formulaires pour une demande sans comparution sont parfois diff\u00e9rents de ceux utilis\u00e9s pour une demande ordinaire. Vous pouvez trouver tous les formulaires judiciaires sur <a href=\"https:\/\/www.albertacourts.ca\/kb\/areas-of-law\/family\/family-law-forms\">le site Web de la Cour du Banc du Roi<\/a> (en anglais seulement). Si vous avez besoin de plus d\u2019aide, <a href=\"https:\/\/family.cplea.ca\/fr\/trouver-un-soutien-juridique\/\">obtenez de l\u2019aide juridique<\/a>.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"ghostkit-accordion-item\" data-accordion=\"accordion-les-procedures-exclues\"><div class=\"ghostkit-accordion-item-heading\"><button type=\"button\" id=\"accordion-les-procedures-exclues-button\" aria-expanded=\"false\" aria-controls=\"accordion-les-procedures-exclues-content\"><span class=\"ghostkit-accordion-item-label\"><strong>Les proc\u00e9dures exclues<\/strong><\/span><span class=\"ghostkit-accordion-item-collapse\"><svg class=\"ghostkit-svg-icon\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M9.21967 6.2197C9.51256 5.9268 9.98744 5.9268 10.2803 6.2197L15.5303 11.4697C15.8232 11.7626 15.8232 12.2374 15.5303 12.5303L10.2803 17.7803C9.98744 18.0732 9.51256 18.0732 9.21967 17.7803C8.92678 17.4874 8.92678 17.0126 9.21967 16.7197L13.9393 12L9.21967 7.2803C8.92678 6.9874 8.92678 6.5126 9.21967 6.2197Z\" fill=\"currentColor\"><\/path><\/svg><\/span><\/button><\/div><div id=\"accordion-les-procedures-exclues-content\" class=\"ghostkit-accordion-item-content is-layout-flow wp-block-ghostkit-accordion-item-is-layout-flow\" role=\"region\" aria-labelledby=\"accordion-les-procedures-exclues-button\">\n<p>Certaines questions particuli\u00e8res font l\u2019objet de proc\u00e9dures sp\u00e9cifiques pour leur r\u00e9solution, notamment les suivantes :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>faire une demande <a href=\"https:\/\/family.cplea.ca\/fr\/article\/que-faire-en-cas-de-violence-familiale\/\">d\u2019ordonnance de protection<\/a> ou lorsqu\u2019il y a des pr\u00e9occupations li\u00e9es \u00e0 des agressions sexuelles<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>les situations o\u00f9 le tribunal a autoris\u00e9 l\u2019utilisation d\u2019une demande urgente<\/li>\n\n\n\n<li>faire <a href=\"https:\/\/family.cplea.ca\/fr\/article\/travailler-avec-une-mere-porteuse\/\">une demande d\u2019ordonnance de gestation pour autrui<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/family.cplea.ca\/fr\/article\/adopter-un-enfant\/\">adopter un enfant<\/a><\/li>\n\n\n\n<li>les appels de d\u00e9cisions de la Cour de justice de l\u2019Alberta<\/li>\n\n\n\n<li>obtenir ou modifier <a href=\"https:\/\/family.cplea.ca\/fr\/article\/regles-concernant-la-pension-alimentiare-pour-enfants\/\">une ordonnance de pension alimentaire pour enfants<\/a> lorsque l\u2019un des parents vit dans une autre province<\/li>\n\n\n\n<li>enregistrer une ordonnance de soutien rendue par un tribunal \u00e0 l\u2019ext\u00e9rieur de l\u2019Alberta<\/li>\n\n\n\n<li>les dossiers o\u00f9 une personne a emmen\u00e9 un enfant hors du Canada sans permission, en vertu de <em>International Child Abduction Act<\/em> (la loi de l\u2019Alberta sur l\u2019enl\u00e8vement international d\u2019enfants), aussi appel\u00e9e la Convention de La Haye<\/li>\n\n\n\n<li>les dossiers concernant les prestations et aides gouvernementales en vertu de la <em>Income and Employment Supports Act<\/em><\/li>\n\n\n\n<li>les dossiers en vertu de la <em>Vital Statistics Act<\/em> lorsque personne ne conteste la situation<\/li>\n\n\n\n<li>les dossiers visant \u00e0 faire respecter des ordonnances et ententes familiales en vertu de <em>la Family Orders and Agreements Enforcement Assistance Act<\/em> du Canada<\/li>\n\n\n\n<li>les dossiers visant \u00e0 faire respecter des ordonnances et ententes de soutien en vertu de la <em>Maintenance Enforcement Act<\/em> de l\u2019Alberta<\/li>\n\n\n\n<li>les demandes au tribunal concernant une sentence arbitrale<\/li>\n<\/ul>\n\n\n\n<p>Vous devez utiliser la bonne demande pr\u00e9vue pour chaque type de probl\u00e8me. Pour en savoir plus sur chaque demande judiciaire, <a href=\"https:\/\/family.cplea.ca\/fr\/trouver-un-soutien-juridique\/\">obtenez de l\u2019aide juridique<\/a>.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"ghostkit-accordion-item\" data-accordion=\"accordion-procedure-familiale-ordinaire\"><div class=\"ghostkit-accordion-item-heading\"><button type=\"button\" id=\"accordion-procedure-familiale-ordinaire-button\" aria-expanded=\"false\" aria-controls=\"accordion-procedure-familiale-ordinaire-content\"><span class=\"ghostkit-accordion-item-label\"><strong>Proc\u00e9dure familiale ordinaire<\/strong><\/span><span class=\"ghostkit-accordion-item-collapse\"><svg class=\"ghostkit-svg-icon\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M9.21967 6.2197C9.51256 5.9268 9.98744 5.9268 10.2803 6.2197L15.5303 11.4697C15.8232 11.7626 15.8232 12.2374 15.5303 12.5303L10.2803 17.7803C9.98744 18.0732 9.51256 18.0732 9.21967 17.7803C8.92678 17.4874 8.92678 17.0126 9.21967 16.7197L13.9393 12L9.21967 7.2803C8.92678 6.9874 8.92678 6.5126 9.21967 6.2197Z\" fill=\"currentColor\"><\/path><\/svg><\/span><\/button><\/div><div id=\"accordion-procedure-familiale-ordinaire-content\" class=\"ghostkit-accordion-item-content is-layout-flow wp-block-ghostkit-accordion-item-is-layout-flow\" role=\"region\" aria-labelledby=\"accordion-procedure-familiale-ordinaire-button\">\n<p>Vous devez recourir \u00e0 la proc\u00e9dure familiale ordinaire si <strong>toutes<\/strong> les conditions suivantes sont r\u00e9unies :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Vous avez besoin de l\u2019aide du tribunal pour r\u00e9gler une question de droit de la famille.<\/li>\n\n\n\n<li>Vous voulez r\u00e9gler, ou vous \u00eates d\u00e9j\u00e0 en train de r\u00e9gler, des questions familiales \u00e0 la Cour du Banc du Roi.<\/li>\n\n\n\n<li>Votre situation <strong>ne rel\u00e8ve pas<\/strong> de la proc\u00e9dure urgente, de la proc\u00e9dure de demande sans comparution ou des proc\u00e9dures exclues.&nbsp;<\/li>\n<\/ul>\n<\/div><\/div>\n<\/div>\n\n\n\n<p><strong>La proc\u00e9dure familiale ordinaire traite la plupart des questions familiales, telles que le partage des biens familiaux, la pension alimentaire pour enfants ou pour conjoint\/partenaire, ainsi que le temps parental. Le reste de cette page explique les diff\u00e9rentes \u00e9tapes de la proc\u00e9dure familiale ordinaire.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Quatre \u00e9tapes obligatoires avant de se pr\u00e9senter au tribunal<\/h2>\n\n\n\n<p>Avant de commencer une proc\u00e9dure familiale ordinaire, vous devez remplir quatre \u00e9tapes obligatoires. Si vous avez une bonne raison pour laquelle vous ne pouvez pas remplir une ou plusieurs de ces \u00e9tapes, vous devez demander \u00e0 un juge de les exempter ou de les reporter.<\/p>\n\n\n\n<p>Les quatre \u00e9tapes sont les suivantes :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Suivre le cours Le r\u00f4le parental apr\u00e8s la s\u00e9paration<\/li>\n\n\n\n<li>Essayer de r\u00e9gler votre diff\u00e9rend \u00e0 l\u2019ext\u00e9rieur du tribunal<\/li>\n\n\n\n<li>Partager vos informations financiers avec l\u2019autre personne<\/li>\n\n\n\n<li>Rencontrer un conseiller du tribunal en droit de la famille si vous n\u2019avez pas d\u2019avocat<\/li>\n<\/ol>\n\n\n\n<p>Pour en savoir plus sur chaque \u00e9tape, consultez la page <a href=\"https:\/\/family.cplea.ca\/fr\/article\/obtenir-ou-repondre-a-une-ordonnance-du-tribunal\/\">Obtenir ou r\u00e9pondre \u00e0 une ordonnance du tribunal<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Engager une instance<\/h2>\n\n\n\n<p>Si vous n\u2019avez pas d\u00e9j\u00e0 un dossier devant la Cour du Banc du Roi, appel\u00e9e <strong>instance<\/strong>, vous ou l\u2019autre partie devez en engager une.<br>Le <strong>demandeur<\/strong> est la personne qui d\u00e9pose le document pour commencer le dossier, appel\u00e9 le <strong>document de d\u00e9part<\/strong>. Le <strong>d\u00e9fendeur<\/strong> est la personne qui re\u00e7oit ce document et qui y r\u00e9pond. Vous ou l\u2019autre personne pouvez commencer une instance en utilisant l\u2019un des documents de d\u00e9part d\u00e9crits dans le tableau ci-dessous.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th><mark style=\"background-color:#BCC78F\" class=\"has-inline-color\">Commencement document<\/mark><\/th><th><mark style=\"background-color:#BCC78F\" class=\"has-inline-color\">Response document<\/mark><\/th><th><mark style=\"background-color:#BCC78F\" class=\"has-inline-color\">When to use<\/mark><\/th><\/tr><\/thead><tbody><tr><td><br><strong>D\u00e9claration en divorce <\/strong>ou<strong> D\u00e9claration en divorce et en partage des biens familiaux<\/strong><\/td><td><strong><strong>D\u00e9fense<\/strong><\/strong><\/td><td>D\u00e9poser une demande de divorce contre votre conjoint en vertu de la <em>Loi sur le divorce<\/em>.<br><br>Pour en savoir plus sur la fa\u00e7on de commencer une instance avec ce document, consultez la page <a href=\"https:\/\/family.cplea.ca\/fr\/article\/obtenir-un-divorce\/\">Obtenir un divorce<\/a>.<\/td><\/tr><tr><td><strong><br><strong>D\u00e9claration en partage des biens familiaux<\/strong><\/strong><\/td><td><strong><strong><strong>D\u00e9fense<\/strong><\/strong><\/strong><\/td><td>Pour partager les biens en vertu de la <em>Family Property Act<\/em> (la loi sur les biens familiaux de l\u2019Alberta) si vous ne demandez pas le divorce.<br><br>Pour en savoir plus sur la fa\u00e7on de commencer une instance avec ce document, consultez la page <a href=\"https:\/\/family.cplea.ca\/fr\/article\/lorsque-vous-ne-parvenez-pas-a-vousmettre-daccrord-sur-la-repartition-de-vos-actifs-et-de-vos-dettes\/\">Lorsque vous ne parvenez pas \u00e0 vous mettre d\u2019accord sur la r\u00e9partition de vos actifs et de vos dettes<\/a>.<\/td><\/tr><tr><td><strong><strong>Demande \u2013 Family Law Act<\/strong><\/strong><\/td><td><strong><strong>R\u00e9ponse &#8211; Family Law Act<\/strong><\/strong><\/td><td>Pour traiter des questions en vertu de la <em>Family Law Act<\/em> (la loi sur le droit de la famille de l\u2019Alberta) si vous ne demandez pas le divorce.<br><br>Pour en savoir plus sur la fa\u00e7on de commencer une instance avec ce document, consultez la page <a href=\"https:\/\/family.cplea.ca\/fr\/article\/obtenir-ou-repondre-a-une-ordonnance-du-tribunal\/\">Obtenir ou r\u00e9pondre \u00e0 une ordonnance du tribunal<\/a>.<\/td><\/tr><tr><td><strong>Originating Application<\/strong>&nbsp;et&nbsp;<strong>Affidavit<\/strong><br><br><strong>(<\/strong>une demande introductive; les formulaires en anglais seulement)<\/td><td><strong>Affidavit<\/strong><br>Plus documents facultatifs :<br><strong>Application \u2013 Civil<\/strong> et <strong>Affidavit<\/strong><br><br>(une d\u00e9claration sous serment et une demande \u2013 civil; les formulaires en anglais seulement)<br><\/td><td>Pour certains probl\u00e8mes pr\u00e9cis, comme faire <a href=\"https:\/\/family.cplea.ca\/fr\/article\/que-faire-en-cas-de-violence-familiale\/\">une demande d\u2019ordonnance de protection de la Cour du Banc du Roi<\/a>, <a href=\"https:\/\/family.cplea.ca\/fr\/article\/quarrive-t-il-a-votre-maison\/\">la possession exclusive d\u2019un domicile ou le partage et la vente d\u2019un domicile<\/a>.<br><br><a href=\"https:\/\/family.cplea.ca\/fr\/trouver-un-soutien-juridique\/\">Obtenez de l\u2019aide juridique<\/a> pour en savoir plus sur la fa\u00e7on de commencer une instance avec ce document.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>Le demandeur doit d\u00e9poser le document introductif aupr\u00e8s du tribunal, puis le <a href=\"https:\/\/family.cplea.ca\/fr\/article\/signification-des-documents-judiciaires\/\">signifier<\/a> au d\u00e9fendeur. Le d\u00e9fendeur a la possibilit\u00e9 de r\u00e9pondre en d\u00e9posant et en signifiant le document de r\u00e9ponse appropri\u00e9.<\/p>\n\n\n\n<p><strong>Si vous demandez au tribunal de rendre une ordonnance<\/strong>, l\u2019\u00e9tape suivante est la conf\u00e9rence obligatoire de triage (MIT Conference).<\/p>\n\n\n\n<p><strong>Si vous ne demandez pas au tribunal de rendre une ordonnance<\/strong>, vous n\u2019avez pas \u00e0 participer \u00e0 une conf\u00e9rence obligatoire de triage. Par exemple, vous pouvez avoir d\u00e9pos\u00e9 une <strong>d\u00e9claration de demande<\/strong> afin de ne pas perdre le d\u00e9lai de prescription, ou vous avoir engag\u00e9 une instance alors que vous et l\u2019autre partie convenez de tenter de r\u00e9soudre vos diff\u00e9rends \u00e0 l\u2019amiable, hors du tribunal. Si, \u00e0 un moment donn\u00e9, vous avez besoin d\u2019une ordonnance du tribunal, vous poursuivrez la proc\u00e9dure familiale ordinaire en participant \u00e0 une conf\u00e9renceobligatoire de triage (MIT Conference).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conf\u00e9rence obligatoire de triage (MIT Conference)<\/h2>\n\n\n\n<p>L\u2019objectif d\u2019une conf\u00e9rence obligatoire de triage (Mandatory Intake Triage Conference ou MIT Conference) est qu\u2019un juge rende des ordonnances provisoires (temporaires) et aide votre dossier \u00e0 avancer vers la prochaine \u00e9tape la plus appropri\u00e9e.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Remplir le dossier de la conf\u00e9rence obligatoire de triage<\/h3>\n\n\n\n<p>Pour que le tribunal fixe une date de conf\u00e9rence obligatoire de triage, le demandeur et le d\u00e9fendeur doivent tous les deux d\u00e9poser d\u2019autres documents aupr\u00e8s du tribunal et les signifier \u00e0 l\u2019autre personne.<\/p>\n\n\n\n<p>Le demandeur doit remplir un dossier de conf\u00e9rence obligatoire de triage (<strong>MIT Package<\/strong>), puis le d\u00e9poser aupr\u00e8s du tribunal et le signifier au d\u00e9fendeur. Le d\u00e9fendeur a ensuite 2 semaines pour r\u00e9pondre en remplissant ses propres documents, en les d\u00e9posant aupr\u00e8s du tribunal et en les signifiant au demandeur. Le demandeur peut aussi choisir de r\u00e9pondre aux documents du d\u00e9fendeur.<br>Pour chaque document de d\u00e9part ou de r\u00e9ponse, suivez la proc\u00e9dure indiqu\u00e9e dans la colonne \u00ab Quand l\u2019utiliser \u00bb du tableau ci-dessus.<\/p>\n\n\n\n<p>Le dossier MIT du demandeur doit inclure les documents suivants, que vous pouvez consulter sur <a href=\"https:\/\/albertacourts.ca\/kb\/areas-of-law\/family\/family-law-forms\">le site Web des tribunaux de l\u2019Alberta<\/a> en anglais seulement :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Proof of Mandatory Requirements<\/strong> &#8211; un formulaire rempli de preuve des exigences obligatoires (ou une d\u00e9rogation ou un report des exigences obligatoires accord\u00e9 par un juge)<\/li>\n\n\n\n<li>votre document de d\u00e9part d\u00e9pos\u00e9<\/li>\n\n\n\n<li>un <strong>affidavit de signification<\/strong> (Affidavit of Service) rempli pour prouver que le document introductif a \u00e9t\u00e9 correctement signifi\u00e9 \u00e0 l\u2019autre partie<\/li>\n\n\n\n<li>votre <strong>d\u00e9claration de divulgation financi\u00e8re<\/strong> (Financial Disclosure Statement) compl\u00e9t\u00e9e<\/li>\n\n\n\n<li>si vous avez d\u00e9j\u00e0 signifi\u00e9 votre <strong>dossier de divulgation financi\u00e8re<\/strong> \u00e0 l\u2019autre partie, un <strong>affidavit de signification<\/strong> rempli pour en prouver la bonne signification. Vous pouvez \u00e9galement signifier votre dossier de divulgation financi\u00e8re pour la premi\u00e8re fois dans le cadre de votre dossier MIT<\/li>\n\n\n\n<li><strong>Request for Mandatory Intake Conference Form<\/strong> &#8211; un formulaire de demande de conf\u00e9rence obligatoire de triage initial (MIT)<\/li>\n\n\n\n<li><strong>Mandatory Intake Triage (MIT) Summary Form<\/strong> &#8211; un formulaire de r\u00e9sum\u00e9 de la conf\u00e9rence obligatoire de triage (MIT)<\/li>\n\n\n\n<li>si vous souhaitez que le tribunal rende une ordonnance sur une question, les documents n\u00e9cessaires pour pr\u00e9senter cette demande. Vous devez inclure <strong>toutes les demandes sur lesquelles vous souhaitez obtenir une ordonnance<\/strong> afin de ne pas retarder le processus ult\u00e9rieurement en soulevant de nouvelles questions. Pour savoir quels documents sont requis, consultez la page <a href=\"https:\/\/family.cplea.ca\/fr\/article\/obtenir-ou-repondre-a-une-ordonnance-du-tribunal\/\">Obtenir ou r\u00e9pondre \u00e0 une ordonnance du tribunal<\/a>.<\/li>\n<\/ol>\n\n\n\n<p>Le demandeur doit d\u00e9poser le dossier MIT aupr\u00e8s du tribunal. Une fois que vous avez r\u00e9cup\u00e9r\u00e9 le dossier MIT d\u00e9pos\u00e9 du tribunal, vous devez le signifier \u00e0 l\u2019autre partie. Ensuite, vous devez remplir et d\u00e9poser un nouvel <strong>affidavit de signification<\/strong> pour prouver que le dossier MIT a \u00e9t\u00e9 correctement signifi\u00e9.<\/p>\n\n\n\n<p>Une fois que le demandeur a signifi\u00e9 le dossier MIT au d\u00e9fendeur, le d\u00e9fendeur a 2 semaines pour r\u00e9pondre. R\u00e9pondre au dossier MIT signifie remplir, d\u00e9poser aupr\u00e8s du tribunal et signifier au demandeur les documents suivants :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Proof of Mandatory Requriements<\/strong> &#8211; un formulaire rempli de preuve des exigences obligatoires (ou une d\u00e9rogation ou un report des exigences obligatoires accord\u00e9 par un juge)<\/li>\n\n\n\n<li>Votre <strong>d\u00e9claration de divulgation financi\u00e8re<\/strong> (Financial Disclosure Statement) compl\u00e9t\u00e9e<\/li>\n\n\n\n<li>Votre r\u00e9ponse au document de d\u00e9part<\/li>\n\n\n\n<li>Un <strong>affidavit de signification<\/strong> rempli pour prouver que vous avez correctement signifi\u00e9 votre d\u00e9claration de divulgation financi\u00e8re et vos documents de r\u00e9ponse<\/li>\n<\/ol>\n\n\n\n<p>Une fois que tous les documents ont \u00e9t\u00e9 d\u00e9pos\u00e9s et signifi\u00e9s, un greffier du tribunal examine le dossier MIT. Vous recevrez un courriel pour vous dire si le tribunal a accept\u00e9 les documents ou s\u2019il en manque.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Planifier la conf\u00e9rence MIT<\/h3>\n\n\n\n<p>Une fois que le tribunal accepte le dossier de conf\u00e9rence obligatoire de triage (MIT), vous et l\u2019autre personne avez 30 jours pour r\u00e9server une conf\u00e9rence obligatoire de triage. Le tribunal vous enverra un formulaire de r\u00e9servation par courriel. Si vous ne r\u00e9servez pas de conf\u00e9rence obligatoire de triage dans les 30 jours, vous devrez recommencer le processus et red\u00e9poser tout le dossier MIT.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Participer \u00e0 la conf\u00e9rence obligatoire de triage<\/h3>\n\n\n\n<p>The MIT Conference is a one-hour meeting between you, the other person and a justice. The conference La conf\u00e9rence obligatoire de triage est une rencontre d\u2019une heure entre vous, l\u2019autre personne et un juge. La conf\u00e9rence a lieu dans une salle d\u2019audience et est enregistr\u00e9e, ce qui signifie qu\u2019elle fait partie du dossier judiciaire de votre cause.<\/p>\n\n\n\n<p>Le juge qui pr\u00e9side votre conf\u00e9rence obligatoire de triage, appel\u00e9 <strong>le juge de la MIT<\/strong>, demeure assign\u00e9 \u00e0 votre dossier jusqu\u2019au proc\u00e8s, si votre cause se rend jusque-l\u00e0.<\/p>\n\n\n\n<p>Voici quelques exemples de ce que le juge de la MIT peut faire pendant la conf\u00e9rence :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>rendre une ordonnance provisoire (temporaire) concernant <a href=\"https:\/\/family.cplea.ca\/fr\/article\/etre-parent-ou-tuteur\/\">le temps parental<\/a> ou <a href=\"https:\/\/family.cplea.ca\/fr\/article\/regles-concernant-la-pension-alimentiare-pour-enfants\/\">la pension alimentaire pour enfants<\/a><\/li>\n\n\n\n<li>rendre une ordonnance sur les proc\u00e9dures du tribunal, comme fixer des dates limites pour que vous et l\u2019autre personne d\u00e9posiez des documents<\/li>\n\n\n\n<li><a href=\"https:\/\/family.cplea.ca\/fr\/article\/rendre-une-ordonnance-par-consentement\/\">rendre une ordonnance par consentement<\/a><\/li>\n\n\n\n<li>aider \u00e0 r\u00e9gler des questions, si vous \u00eates tous les deux dispos\u00e9s \u00e0 le faire<\/li>\n<\/ul>\n\n\n\n<p>Le juge de la MIT examine aussi si vous avez des besoins particuliers pour l\u2019\u00e9tape suivante, la conf\u00e9rence de r\u00e8glement. Par exemple, certaines personnes peuvent avoir des besoins li\u00e9s \u00e0 la s\u00e9curit\u00e9 en raison de la violence familiale, ou des besoins culturels, comme une c\u00e9r\u00e9monie de purification par la fum\u00e9e. D\u2019autres peuvent avoir besoin de mesures d\u2019adaptation, comme l\u2019acc\u00e8s en fauteuil roulant ou un interpr\u00e8te.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Apr\u00e8s la conf\u00e9rence obligatoire de triage<\/h3>\n\n\n\n<p>Apr\u00e8s la conf\u00e9rence obligatoire de triage, le <strong>juge de la MIT<\/strong> pr\u00e9pare un <strong>rapport de la conf\u00e9rence obligatoire de triage<\/strong>, que le tribunal vous envoie par courriel, \u00e0 vous et \u00e0 l\u2019autre personne. Le rapport indique les dates limites \u00e0 respecter et vous donne la permission de fixer les prochaines \u00e9tapes, s\u2019il y a lieu.<\/p>\n\n\n\n<p>Si ni vous ni l\u2019autre personne n\u2019avez d\u2019avocat, un greffier du tribunal vous aidera \u00e0 pr\u00e9parer les ordonnances rendues par le juge. Si l\u2019un de vous ou vous deux avez un avocat, c\u2019est un avocat qui s\u2019en chargera.<\/p>\n\n\n\n<p><strong>Si vous et l\u2019autre personne r\u00e9glez toutes les questions<\/strong> lors de la conf\u00e9rence obligatoire de triage, il n\u2019y a aucune autre \u00e9tape \u00e0 suivre.<\/p>\n\n\n\n<p><strong>Si certains probl\u00e8mes ne sont pas r\u00e9gl\u00e9s<\/strong>, votre dossier passe \u00e0 une conf\u00e9rence de r\u00e8glement. Dans certains cas, au lieu d\u2019une conf\u00e9rence de r\u00e8glement, le juge de la MIT peut vous diriger vers une autre conf\u00e9rence ou d\u00e9cider que votre dossier doit aller directement au proc\u00e8s.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conf\u00e9rence de r\u00e8glement<\/h2>\n\n\n\n<p>L\u2019objectif de la conf\u00e9rence de r\u00e8glement est qu\u2019un juge vous aide, vous et l\u2019autre personne, \u00e0 parvenir \u00e0 une entente sur toutes ou certaines des questions.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Se pr\u00e9parer \u00e0 la conf\u00e9rence de r\u00e8glement<\/h3>\n\n\n\n<p>Vous pouvez r\u00e9server une conf\u00e9rence de r\u00e8glement une fois que vous avez respect\u00e9 toutes les dates limites fix\u00e9es par le juge de la MIT. Si le juge de la MIT n\u2019a fix\u00e9 aucune date limite, vous pouvez r\u00e9server une conf\u00e9rence de r\u00e8glement imm\u00e9diatement apr\u00e8s la conf\u00e9rence obligatoire de triage.<\/p>\n\n\n\n<p>Vous et l\u2019autre partie devez soumettre ensemble un seul formulaire (<strong>Joint Request for Settlement Conference<\/strong>) de demande conjointe de date pour la conf\u00e9rence de r\u00e8glement.<\/p>\n\n\n\n<p>Chacun de vous doit aussi pr\u00e9parer un <strong>m\u00e9moire de r\u00e8glement<\/strong>. Il s\u2019agit d\u2019une lettre adress\u00e9e au tribunal qui comprend :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>une liste des questions en litige entre vous et l\u2019autre personne<\/li>\n\n\n\n<li>votre position sur la fa\u00e7on de r\u00e9gler chaque question<\/li>\n\n\n\n<li>un r\u00e9sum\u00e9 des faits et des preuves sur lesquels vous vous appuyez pour soutenir votre position<\/li>\n\n\n\n<li>toute jurisprudence sur laquelle vous vous appuyez pour soutenir votre position<\/li>\n\n\n\n<li>tout calcul li\u00e9 \u00e0 la pension alimentaire pour enfants, \u00e0 la pension alimentaire pour conjoint ou partenaire, ou au partage des biens<\/li>\n<\/ul>\n\n\n\n<p>Vous devez d\u00e9poser le m\u00e9moire de r\u00e8glement aupr\u00e8s du tribunal, puis le <a href=\"https:\/\/family.cplea.ca\/fr\/article\/signification-des-documents-judiciaires\/\">signifier<\/a> \u00e0 l\u2019autre personne <strong>au moins 14 jours avant<\/strong> la date de la conf\u00e9rence de r\u00e8glement.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Participer \u00e0 la conf\u00e9rence de r\u00e8glement<\/h3>\n\n\n\n<p>La conf\u00e9rence de r\u00e8glement est une rencontre en personne entre vous, l\u2019autre personne et un juge diff\u00e9rent de celui de la MIT. Elle dure environ 2 heures et demie.<\/p>\n\n\n\n<p>La Conf\u00e9rence de r\u00e8glement est g\u00e9n\u00e9ralement non contraignante, ce qui signifie que le juge ne prendra aucune d\u00e9cision que vous seriez l\u00e9galement tenu de suivre. Vous, l\u2019autre personne et le juge pouvez toutefois convenir ensemble que la conf\u00e9rence de r\u00e8glement soit contraignante en signant un accord contraignant de Conf\u00e9rence de r\u00e8glement (<strong>Binding Settlement Conference Agreement<\/strong>).&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Apr\u00e8s la conf\u00e9rence de r\u00e8glement<\/h3>\n\n\n\n<p>Apr\u00e8s la conf\u00e9rence de r\u00e8glement, le juge r\u00e9dige un <strong>rapport de la conf\u00e9rence de r\u00e8glement<\/strong>, que le tribunal vous enverra par courriel. Si certains points ont \u00e9t\u00e9 r\u00e9gl\u00e9s, le rapport pr\u00e9cisera les ententes conclues entre vous et<strong> <\/strong>l\u2019autre personne.<\/p>\n\n\n\n<p>Si <strong>tous vos points en litige sont r\u00e9gl\u00e9s<\/strong> lors de la conf\u00e9rence de r\u00e8glement, le greffier du tribunal (si aucun de vous n\u2019a d\u2019avocat) ou un avocat (si l\u2019un d\u2019entre vous est repr\u00e9sent\u00e9) pr\u00e9parera les ordonnances judiciaires \u00e9non\u00e7ant les ententes convenues.<br>Si <strong>certains points demeurent en litige<\/strong> apr\u00e8s la Conf\u00e9rence de r\u00e8glement, l\u2019\u00e9tape suivante consiste \u00e0<strong> <\/strong>pr\u00e9parer le proc\u00e8s<strong>.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Proc\u00e8s<\/h2>\n\n\n\n<p>Le proc\u00e8s est la derni\u00e8re \u00e9tape pour r\u00e9gler toutes les questions encore en litige entre vous et l\u2019autre personne. Lors d\u2019un proc\u00e8s, un juge entend la preuve pr\u00e9sent\u00e9e par les deux parties et rend une d\u00e9cision finale.<\/p>\n\n\n\n<p>Le tribunal vise \u00e0 <strong>programmer le proc\u00e8s dans un d\u00e9lai maximal de 18 mois<\/strong> apr\u00e8s la Conf\u00e9rence de r\u00e8glement. Pour en savoir plus sur ce \u00e0 quoi vous attendre au tribunal, consultez la page <a href=\"https:\/\/family.cplea.ca\/fr\/article\/avant-d-aller-au-tribunal\/\">Avant d\u2019aller au tribunal<\/a>.<\/p>\n\n\n\n<p>Avant le proc\u00e8s, le tribunal peut vous ordonner de suivre une ou plusieurs des trois \u00e9tapes suivantes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Plan de litige<\/h3>\n\n\n\n<p>Un plan de litige d\u00e9crit toutes les \u00e9tapes que vous et l\u2019autre personne devez suivre avant le proc\u00e8s, ainsi que les dates limites pour chaque \u00e9tape. Si vous et l\u2019autre personne \u00eates tous deux repr\u00e9sent\u00e9s par un avocat, ce sont vos avocats qui \u00e9tabliront le plan de litige. Si l\u2019un de vous n\u2019a pas d\u2019avocat, les avocats de r\u00e8glement (Resolution Counsel), engag\u00e9s par le tribunal, vous aideront \u00e0 pr\u00e9parer le plan de litige.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Conf\u00e9rence de dossier \u2013 R\u00e8gle 4.10<\/h3>\n\n\n\n<p>Si vous et l\u2019autre personne n\u2019arrivez pas \u00e0 vous entendre sur le plan de litige, vous devrez tous les deux participer \u00e0 une conf\u00e9rence de dossier en vertu de la r\u00e8gle 4.10 avec un juge. L\u2019objectif de cette conf\u00e9rence est de mettre en place le plan de litige.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Conf\u00e9rence pr\u00e9paratoire au proc\u00e8s<\/h3>\n\n\n\n<p>Dans certains cas, le m\u00eame juge qui a tenu la conf\u00e9rence obligatoire de triage ou la conf\u00e9rence de dossier tiendra une conf\u00e9rence pr\u00e9paratoire au proc\u00e8s (Pre-Trial Conference ou PTC) avec vous et l\u2019autre personne (et vos avocats, si l\u2019un de vous en a un). La conf\u00e9rence pr\u00e9paratoire au proc\u00e8s aura lieu au moins 90 jours avant la date pr\u00e9vue du proc\u00e8s. L\u2019objectif de la conf\u00e9rence pr\u00e9paratoire au proc\u00e8s est de s\u2019assurer que vous \u00eates tous les deux pr\u00eats pour le proc\u00e8s.<\/p>\n\n\n\n<div class=\"wp-block-group is-style-next-steps is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Prochaines \u00e9tapes<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Apprenez <a href=\"https:\/\/family.cplea.ca\/fr\/article\/moyens-de-resoudre-les-differends\/\">les fa\u00e7ons de r\u00e9gler les diff\u00e9rends<\/a>, y compris comment diff\u00e9rents professionnels peuvent vous aider<\/li>\n\n\n\n<li><a href=\"https:\/\/family.cplea.ca\/fr\/article\/avant-d-aller-au-tribunal\/\">Pr\u00e9parez-vous pour le tribunal<\/a> afin de savoir \u00e0 quoi vous attendre lorsque vous y allez<\/li>\n\n\n\n<li><a href=\"https:\/\/family.cplea.ca\/fr\/article\/rendre-une-ordonnance-par-consentement\/\">Faire une ordonnance par consentement<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/family.cplea.ca\/fr\/article\/signification-des-documents-judiciaires\/\">Signifier des documents judiciaires<\/a><\/li>\n\n\n\n<li>Trouvez plus d\u2019informations d\u00e9taill\u00e9es sur les proc\u00e9dures du tribunal <a href=\"https:\/\/www.albertacourts.ca\/kb\/areas-of-law\/family\/family-focused-protocol\">sur son site Web<\/a><\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-style-potential-issues is-layout-flow wp-block-group-is-layout-flow\" style=\"padding-top:var(--wp--preset--spacing--30);padding-bottom:0\">\n<h2 class=\"wp-block-heading\" id=\"potential-issues\">Probl\u00e8mes potentiels<\/h2>\n\n<div class=\"acf-innerblocks-container\">\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"acf-innerblocks-container\">\n\n<p><strong><strong>Une personne ne r\u00e9pond pas au dossier MIT.<\/strong><\/strong><\/p>\n\n\n\n<p>Une fois que vous avez signifi\u00e9 le dossier MIT \u00e0 l\u2019autre personne, celle-ci a 14 jours pour r\u00e9pondre. Si elle ne r\u00e9pond pas dans ce d\u00e9lai, il pourrait \u00eatre possible de programmer une conf\u00e9rence MIT sans son consentement.<\/p>\n\n<\/div>\n<\/div>\n\n<\/div>\n<\/div>\n<!-- \/wp:group --><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Traiter des questions de droit de la famille \u00e0 la Cour du Banc du Roi.<\/p>\n","protected":false},"featured_media":1833,"template":"","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":""},"topic":[],"article-type":[],"class_list":["post-2828","article","type-article","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Se rendre \u00e0 la Cour du Banc du Roi - CPLEA Family Law<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/family.cplea.ca\/fr\/article\/se-rendre-a-la-cour-du-banc-du-roi\/\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"16 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/article\\\/se-rendre-a-la-cour-du-banc-du-roi\\\/\",\"url\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/article\\\/se-rendre-a-la-cour-du-banc-du-roi\\\/\",\"name\":\"Se rendre \u00e0 la Cour du Banc du Roi - CPLEA Family Law\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/article\\\/se-rendre-a-la-cour-du-banc-du-roi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/article\\\/se-rendre-a-la-cour-du-banc-du-roi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/family.cplea.ca\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/going-to-court.png\",\"datePublished\":\"2025-12-10T04:06:35+00:00\",\"dateModified\":\"2026-01-26T18:01:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/article\\\/se-rendre-a-la-cour-du-banc-du-roi\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/article\\\/se-rendre-a-la-cour-du-banc-du-roi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/article\\\/se-rendre-a-la-cour-du-banc-du-roi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/family.cplea.ca\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/going-to-court.png\",\"contentUrl\":\"https:\\\/\\\/family.cplea.ca\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/going-to-court.png\",\"width\":393,\"height\":332},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/article\\\/se-rendre-a-la-cour-du-banc-du-roi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se rendre \u00e0 la Cour du Banc du Roi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/\",\"name\":\"CPLEA Family Law\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/#organization\",\"name\":\"CPLEA Family Law\",\"url\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/family.cplea.ca\\\/wp-content\\\/uploads\\\/CPLEA-new-web-logo-FR-1-1.png\",\"contentUrl\":\"https:\\\/\\\/family.cplea.ca\\\/wp-content\\\/uploads\\\/CPLEA-new-web-logo-FR-1-1.png\",\"width\":1784,\"height\":273,\"caption\":\"CPLEA Family Law\"},\"image\":{\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CPLEAlberta\",\"https:\\\/\\\/x.com\\\/cplealberta\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se rendre \u00e0 la Cour du Banc du Roi - CPLEA Family Law","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/family.cplea.ca\/fr\/article\/se-rendre-a-la-cour-du-banc-du-roi\/","twitter_misc":{"Est. reading time":"16 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/family.cplea.ca\/fr\/article\/se-rendre-a-la-cour-du-banc-du-roi\/","url":"https:\/\/family.cplea.ca\/fr\/article\/se-rendre-a-la-cour-du-banc-du-roi\/","name":"Se rendre \u00e0 la Cour du Banc du Roi - CPLEA Family Law","isPartOf":{"@id":"https:\/\/family.cplea.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/family.cplea.ca\/fr\/article\/se-rendre-a-la-cour-du-banc-du-roi\/#primaryimage"},"image":{"@id":"https:\/\/family.cplea.ca\/fr\/article\/se-rendre-a-la-cour-du-banc-du-roi\/#primaryimage"},"thumbnailUrl":"https:\/\/family.cplea.ca\/wp-content\/uploads\/2024\/01\/going-to-court.png","datePublished":"2025-12-10T04:06:35+00:00","dateModified":"2026-01-26T18:01:25+00:00","breadcrumb":{"@id":"https:\/\/family.cplea.ca\/fr\/article\/se-rendre-a-la-cour-du-banc-du-roi\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/family.cplea.ca\/fr\/article\/se-rendre-a-la-cour-du-banc-du-roi\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/family.cplea.ca\/fr\/article\/se-rendre-a-la-cour-du-banc-du-roi\/#primaryimage","url":"https:\/\/family.cplea.ca\/wp-content\/uploads\/2024\/01\/going-to-court.png","contentUrl":"https:\/\/family.cplea.ca\/wp-content\/uploads\/2024\/01\/going-to-court.png","width":393,"height":332},{"@type":"BreadcrumbList","@id":"https:\/\/family.cplea.ca\/fr\/article\/se-rendre-a-la-cour-du-banc-du-roi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/family.cplea.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Se rendre \u00e0 la Cour du Banc du Roi"}]},{"@type":"WebSite","@id":"https:\/\/family.cplea.ca\/fr\/#website","url":"https:\/\/family.cplea.ca\/fr\/","name":"CPLEA Family Law","description":"","publisher":{"@id":"https:\/\/family.cplea.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/family.cplea.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/family.cplea.ca\/fr\/#organization","name":"CPLEA Family Law","url":"https:\/\/family.cplea.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/family.cplea.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/family.cplea.ca\/wp-content\/uploads\/CPLEA-new-web-logo-FR-1-1.png","contentUrl":"https:\/\/family.cplea.ca\/wp-content\/uploads\/CPLEA-new-web-logo-FR-1-1.png","width":1784,"height":273,"caption":"CPLEA Family Law"},"image":{"@id":"https:\/\/family.cplea.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CPLEAlberta","https:\/\/x.com\/cplealberta"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/family.cplea.ca\/fr\/wp-json\/wp\/v2\/article\/2828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/family.cplea.ca\/fr\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/family.cplea.ca\/fr\/wp-json\/wp\/v2\/types\/article"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/family.cplea.ca\/fr\/wp-json\/wp\/v2\/media\/1833"}],"wp:attachment":[{"href":"https:\/\/family.cplea.ca\/fr\/wp-json\/wp\/v2\/media?parent=2828"}],"wp:term":[{"taxonomy":"topic","embeddable":true,"href":"https:\/\/family.cplea.ca\/fr\/wp-json\/wp\/v2\/topic?post=2828"},{"taxonomy":"article-type","embeddable":true,"href":"https:\/\/family.cplea.ca\/fr\/wp-json\/wp\/v2\/article-type?post=2828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}