{"id":1962,"date":"2024-01-22T13:27:17","date_gmt":"2024-01-22T20:27:17","guid":{"rendered":"https:\/\/wpml.cplea.ca\/article\/comment-communiquer-avec-lautre-personne\/"},"modified":"2025-08-27T13:10:08","modified_gmt":"2025-08-27T19:10:08","slug":"comment-communiquer-avec-lautre-personne","status":"publish","type":"article","link":"https:\/\/family.cplea.ca\/fr\/article\/comment-communiquer-avec-lautre-personne\/","title":{"rendered":"Comment communiquer avec l&#8217;autre personne"},"content":{"rendered":"\r\n<div class=\"wp-block-group is-style-lead has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\r\n<p>Apr\u00e8s une s\u00e9paration, vous et l&#8217;autre personne pouvez avoir du mal \u00e0 communiquer l&#8217;un avec l&#8217;autre. Mais apprendre \u00e0 communiquer efficacement peut vous aider \u00e0 mieux faire face \u00e0 tout ce qui se passe apr\u00e8s une s\u00e9paration. <\/p>\r\n\r\n\r\n\r\n<p>Si vous avez des enfants ensemble, vous continuerez \u00e0 faire <span class=\"wp-glossary-term-ignore\">partie<\/span> de la vie de l\u2019autre au moins jusqu&#8217;\u00e0 ce que vos enfants atteignent l&#8217;\u00e2ge de 18 ans, surtout si vous avez tous les deux le pouvoir de prendre des d\u00e9cisions \u00e0 leur sujet. Le fait de trouver une fa\u00e7on de coparenter vous permet de mieux \u00e9duquer vos enfants.<\/p>\r\n\r\n\r\n\r\n<p>Si vous \u00eates pr\u00e9occup\u00e9 par la violence familiale ou si vous ne vous sentez pas \u00e0 l&#8217;aise pour communiquer avec l&#8217;autre personne, renseignez-vous sur les <a href=\"https:\/\/family.cplea.ca\/fr\/article\/es-moyens-de-resoudre-les-conflits\/\" data-type=\"article\" data-id=\"454\">autres modes de r\u00e9solution des diff\u00e9rends<\/a>.<\/p>\r\n<\/div>\r\n\r\n\r\n\n<div class=\"wp-block-group is-style-mobile-jumplinks is-style-sidebar ghostkit-d-none ghostkit-d-xl-none ghostkit-d-lg-none ghostkit-d-md-none ghostkit-d-sm-block has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading on-this-page\">Sur cette page<\/h2>\n<ul class=\"toc\"><\/ul>\n<\/div>\n\r\n\r\n\r\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\r\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:75%\" id=\"content\">\r\n<div class=\"wp-block-group is-style-summary is-layout-flow wp-block-group-is-layout-flow\">\r\n<h2 class=\"wp-block-heading\" id=\"need-to-know\">Besoin de savoir<\/h2>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li>Communiquer efficacement avec l&#8217;autre personne est dans l&#8217;int\u00e9r\u00eat sup\u00e9rieur et le bien-\u00eatre de vos enfants.<\/li>\r\n\r\n\r\n\r\n<li>Tous les parents\/tuteurs doivent prendre ensemble les d\u00e9cisions importantes concernant leur enfant, \u00e0 moins qu&#8217;une ordonnance du tribunal n&#8217;en dispose autrement.<\/li>\r\n\r\n\r\n\r\n<li>Apprendre \u00e0 travailler ensemble peut vous aider \u00e0 r\u00e9soudre les probl\u00e8mes plus rapidement sans avoir recours aux tribunaux, ce qui prend du temps et de l&#8217;argent.<\/li>\r\n\r\n\r\n\r\n<li>Soyez poli, restez centr\u00e9 sur le sujet, soyez raisonnable, organis\u00e9 et fiable.<\/li>\r\n\r\n\r\n\r\n<li>\u00c9vitez les insultes, la moquerie, le harc\u00e8lement ou la dispute avec l&#8217;autre personne.<\/li>\r\n<\/ul>\r\n<\/div>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\" id=\"review-your-court-orders\">R\u00e9visez vos ordonnances du tribunal<\/h2>\r\n\r\n\r\n\r\n<p>Si vous avez une <a href=\"https:\/\/family.cplea.ca\/fr\/article\/obtenir-ou-repondre-a-une-ordonnance-du-tribunal\/\" data-type=\"article\" data-id=\"464\">ordonnance du tribunal<\/a> concernant votre famille, relisez-la pour vous assurer que vous avez bien compris ce qu&#8217;elle dit, notamment sur la fa\u00e7on dont vous et l&#8217;autre personne devez communiquer entre vous. Et surtout, respectez les dispositions de l&#8217;ordonnance !<\/p>\r\n\r\n\r\n\n<div class=\"wp-block-group has-border-color block--callout is-style-star has-global-padding is-layout-constrained wp-container-core-group-is-layout-e555385e wp-block-group-is-layout-constrained\" style=\"border-color:#3F3F41;border-width:1px;border-radius:5px\">\n<div class=\"wp-block-group has-background block--callout-header has-global-padding is-layout-constrained wp-container-core-group-is-layout-54baa1d7 wp-block-group-is-layout-constrained\" style=\"border-bottom-color:var(--wp--preset--color--contrast);border-bottom-width:1px;padding-top:0.5em;padding-right:var(--wp--preset--spacing--30);padding-bottom:0.5em;padding-left:var(--wp--preset--spacing--30)\">\n\n<h3 class=\"wp-block-heading\">Si vous avez une ordonnance de protection<\/h3>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-container-core-group-is-layout-a35945ca wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--30);padding-right:var(--wp--preset--spacing--30);padding-bottom:var(--wp--preset--spacing--30);padding-left:var(--wp--preset--spacing--30)\"><div class=\"stack\">\r\n\r\n<p>Votre <a href=\"https:\/\/family.cplea.ca\/fr\/article\/que-faire-en-cas-de-violence-familiale\/#types-dordonnances-de-protection\" data-type=\"article\" data-id=\"453\">ordonnance de protection<\/a> peut limiter ou interdire la communication avec l&#8217;autre personne. Si vous vous sentez \u00e0 l&#8217;aise et en s\u00e9curit\u00e9, vous pouvez demander au tribunal de modifier l&#8217;ordonnance pour vous permettre de communiquer ensemble d&#8217;une certaine mani\u00e8re afin de r\u00e9gler les probl\u00e8mes qui se pr\u00e9sentent.<\/p>\r\n\r\n\r\n\r\n<p>Vous pouvez \u00e9galement demander au tribunal de <a href=\"https:\/\/family.cplea.ca\/fr\/article\/obtenir-ou-repondre-a-une-ordonnance-du-tribunal\/\" data-type=\"article\" data-id=\"464\">rendre ou modifier une ordonnance parentale<\/a> pour vous permettre de prendre des d\u00e9cisions sans l&#8217;autre personne.<\/p>\r\n\r\n<\/div><\/div>\n<\/div>\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\" id=\"set-boundaries\">Fixer des limites<\/h2>\r\n\r\n\r\n\r\n<p>Avant de commencer \u00e0 r\u00e9soudre les probl\u00e8mes, d\u00e9terminez comment et quand vous communiquerez avec l&#8217;autre personne. Le fait de fixer ces limites d\u00e8s le d\u00e9but peut vous aider \u00e0 vous sentir moins stress\u00e9s et d\u00e9pass\u00e9s. <\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading is-style-highlighted\" id=\"choose-a-method-to-communicate\">Choisir une m\u00e9thode de communication<\/h3>\r\n\r\n\r\n\r\n<p>Choisissez un moyen de communiquer entre vous dans les situations non urgentes. Voici quelques options possibles : <\/p>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li>courriel<\/li>\r\n\r\n\r\n\r\n<li>texte<\/li>\r\n\r\n\r\n\r\n<li><span class=\"wp-glossary-term-ignore\">application<\/span> de coparentalit\u00e9<\/li>\r\n\r\n\r\n\r\n<li>calendrier partag\u00e9<\/li>\r\n\r\n\r\n\r\n<li>en personne<\/li>\r\n\r\n\r\n\r\n<li>au t\u00e9l\u00e9phone<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<p>Il est pr\u00e9f\u00e9rable de communiquer par \u00e9crit. Les avantages qui en d\u00e9coulent sont les suivants :<\/p>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li>r\u00e9duire le risque de mauvaise communication<\/li>\r\n\r\n\r\n\r\n<li>donner \u00e0 chaque personne le temps de lire et d&#8217;assimiler le message et de r\u00e9fl\u00e9chir \u00e0 sa r\u00e9ponse avant d&#8217;entamer une conversation<\/li>\r\n\r\n\r\n\r\n<li>cr\u00e9er un dossier de vos tentatives de collaboration si vous avez besoin de l&#8217;aide d&#8217;un professionnel \u00e0 un moment donn\u00e9 ou si vous devez vous adresser \u00e0 un tribunal<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<p>Si vous avez une conversation en personne ou au t\u00e9l\u00e9phone, il est bon d&#8217;envoyer un message de suivi par \u00e9crit qui r\u00e9sume ce que chacun d&#8217;entre vous a dit et ce sur quoi vous vous \u00eates mis d&#8217;accord.<\/p>\r\n\r\n\r\n\n<div class=\"wp-block-group has-border-color block--callout is-style-info has-global-padding is-layout-constrained wp-container-core-group-is-layout-e555385e wp-block-group-is-layout-constrained\" style=\"border-color:#3F3F41;border-width:1px;border-radius:5px\">\n<div class=\"wp-block-group has-background block--callout-header has-global-padding is-layout-constrained wp-container-core-group-is-layout-54baa1d7 wp-block-group-is-layout-constrained\" style=\"border-bottom-color:var(--wp--preset--color--contrast);border-bottom-width:1px;padding-top:0.5em;padding-right:var(--wp--preset--spacing--30);padding-bottom:0.5em;padding-left:var(--wp--preset--spacing--30)\">\n\n<h3 class=\"wp-block-heading\">Des applications pour aider les coparents \u00e0 communiquer<\/h3>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-container-core-group-is-layout-a35945ca wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--30);padding-right:var(--wp--preset--spacing--30);padding-bottom:var(--wp--preset--spacing--30);padding-left:var(--wp--preset--spacing--30)\"><div class=\"stack\">\r\n\r\n<p><a href=\"https:\/\/coparenter.com\/\"><strong>CoParenter<\/strong><\/a> permet aux familles <span class=\"wp-glossary-term-ignore\">d&#8217;acc\u00e9der<\/span> \u00e0 la m\u00e9diation et au coaching en ligne, aux plans de s\u00e9curit\u00e9 li\u00e9s aux soins de sant\u00e9, aux plans parentaux, aux calendriers des vacances et des cong\u00e9s, aux accords, \u00e0 l&#8217;\u00e9ducation et au soutien. CoParenter offre une p\u00e9riode d&#8217;essai gratuite de 30 jours pour tester <span class=\"wp-glossary-term-ignore\">l&#8217;application<\/span>.<\/p>\r\n\r\n\r\n\r\n<p><a href=\"https:\/\/www.ourfamilywizard.com\/\"><strong>Our Family Wizard<\/strong><\/a> aide les parents \u00e0 g\u00e9rer leur emploi du temps, \u00e0 suivre leurs d\u00e9penses, \u00e0 partager des fichiers, \u00e0 envoyer des messages, \u00e0 passer des appels s\u00e9curis\u00e9s et bien plus encore. <span class=\"wp-glossary-term-ignore\">L&#8217;application<\/span> peut \u00eatre essay\u00e9e pendant 30 jours avec une garantie de remboursement.<\/p>\r\n\r\n<\/div><\/div>\n<\/div>\n\r\n\r\n\r\n<h3 class=\"wp-block-heading is-style-highlighted\" id=\"decide-when-to-communicate\">D\u00e9cider quand communiquer<\/h3>\r\n\r\n\r\n\r\n<p>D\u00e9cidez quand et \u00e0 quelle fr\u00e9quence vous communiquerez l&#8217;un avec l&#8217;autre. Une fois par semaine ? Deux fois par semaine ? Une fois par mois ? Le fait de limiter les communications non urgentes \u00e0 un horaire fixe vous permet de mettre de l&#8217;espace entre vous.    <\/p>\r\n\r\n\r\n\r\n<p>Si vous avez des enfants, vous pouvez convenir de ne pas aborder les questions relatives \u00e0 votre s\u00e9paration ou aux d\u00e9cisions parentales lorsque vous allez chercher ou d\u00e9poser vos enfants l&#8217;un chez l&#8217;autre. Cette mesure est b\u00e9n\u00e9fique pour la famille \u00e0 bien des \u00e9gards : <\/p>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li>\u00c7a r\u00e9duit les tensions au moment de chercher ou d\u00e9poser vos enfants<\/li>\r\n\r\n\r\n\r\n<li>\u00c7a supprime la pression qu&#8217;un parent peut ressentir pour avoir une conversation \u00e0 laquelle il n&#8217;est pas pr\u00eat ou pour laquelle il n&#8217;a pas le temps<\/li>\r\n\r\n\r\n\r\n<li>\u00c7a r\u00e9duit les risques que les enfants entendent les conversations des adultes<\/li>\r\n\r\n\r\n\r\n<li>\u00c7a permet une discussion approfondie \u00e0 un autre moment<\/li>\r\n<\/ul>\r\n\r\n\r\n\n<div class=\"wp-block-group has-border-color block--callout is-style-bulb has-global-padding is-layout-constrained wp-container-core-group-is-layout-e555385e wp-block-group-is-layout-constrained\" style=\"border-color:#3F3F41;border-width:1px;border-radius:5px\">\n<div class=\"wp-block-group has-background block--callout-header has-global-padding is-layout-constrained wp-container-core-group-is-layout-54baa1d7 wp-block-group-is-layout-constrained\" style=\"border-bottom-color:var(--wp--preset--color--contrast);border-bottom-width:1px;padding-top:0.5em;padding-right:var(--wp--preset--spacing--30);padding-bottom:0.5em;padding-left:var(--wp--preset--spacing--30)\">\n\n<h3 class=\"wp-block-heading\">Conseils pratiques<\/h3>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-container-core-group-is-layout-a35945ca wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--30);padding-right:var(--wp--preset--spacing--30);padding-bottom:var(--wp--preset--spacing--30);padding-left:var(--wp--preset--spacing--30)\"><div class=\"stack\">\r\n\r\n<p>Ne sauvegardez pas les coordonn\u00e9es de l&#8217;autre personne dans votre t\u00e9l\u00e9phone avec un surnom insultant. M\u00eame si vous trouvez cela dr\u00f4le ou r\u00e9confortant, n&#8217;oubliez pas que d&#8217;autres personnes peuvent voir ce nom, notamment vos enfants, des psychologues, des enseignants ou le tribunal. <\/p>\r\n\r\n<\/div><\/div>\n<\/div>\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\" id=\"set-a-goal-for-each-communication-and-stick-to-it\">Fixer un objectif pour chaque communication et le respecter<\/h2>\r\n\r\n\r\n\r\n<p>Chaque fois que vous communiquez avec l&#8217;autre personne, fixez l&#8217;objectif de la discussion. Par exemple, l&#8217;objectif est-il de prendre une d\u00e9cision pour votre enfant ? S&#8217;agit-il de lui rappeler une \u00e9ch\u00e9ance ou un rendez-vous \u00e0 venir ? Partagez cet objectif avec l&#8217;autre personne afin que vous puissiez tous deux vous pr\u00e9parer et rester concentr\u00e9s pendant la discussion.   <\/p>\r\n\r\n\r\n\r\n<p>Avant de communiquer avec l&#8217;autre personne, prenez le temps de r\u00e9fl\u00e9chir \u00e0 la question et de faire des recherches. Par exemple, si vous prenez une d\u00e9cision concernant votre enfant, r\u00e9fl\u00e9chissez aux <span class=\"wp-glossary-term-ignore\">frais<\/span> encourus, \u00e0 la question de savoir si elle affecte le plan parental actuel et \u00e0 ce que l&#8217;enfant en pense.<\/p>\r\n\r\n\r\n\r\n<p>Pendant votre communication avec l&#8217;autre personne, restez sur le sujet. En vous concentrant sur cet objectif, vous resterez plus calme et moins \u00e9motif. Si vos \u00e9motions prennent le dessus, votre objectif peut se transformer en une volont\u00e9 de faire sentir l&#8217;autre personne d&#8217;une certaine mani\u00e8re, ce qui peut conduire \u00e0 un conflit.  <\/p>\r\n\r\n\r\n\r\n<p>Si vous prenez une d\u00e9cision ensemble, documentez-la. Il peut s&#8217;agir simplement d&#8217;un courriel ou d&#8217;un texte. La d\u00e9cision peut \u00e9galement faire <span class=\"wp-glossary-term-ignore\">partie<\/span> d&#8217;un <a href=\"https:\/\/family.cplea.ca\/fr\/article\/conclure-un-accord-de-separation\/\">accord de s\u00e9paration<\/a> ou d\u2019une <a href=\"https:\/\/family.cplea.ca\/fr\/article\/rendre-une-ordonnance-par-consentement\/\">ordonnance de consentement<\/a>.<\/p>\r\n\r\n\r\n\r\n<p>Si vous avez des enfants ensemble, n&#8217;oubliez pas que les d\u00e9cisions que vous prenez doivent \u00eatre prises dans leur <a href=\"https:\/\/family.cplea.ca\/fr\/article\/le-principe-de-linteret-superieur-de-lenfant\/\" data-type=\"article\" data-id=\"429\">int\u00e9r\u00eat sup\u00e9rieur<\/a>. Lorsque vous communiquez avec l&#8217;autre parent, restez concentr\u00e9 sur votre enfant et non sur votre relation avec l&#8217;autre parent. Cela vous permettra de travailler ensemble, et non l&#8217;un contre l&#8217;autre, dans le but commun de vous occuper au mieux de vos enfants.<\/p>\r\n\r\n\r\n\n<div class=\"wp-block-group is-style-example is-layout-flow wp-block-group-is-layout-flow\">\n<h3 class=\"wp-block-heading\" id=\"example\" style=\"text-transform:uppercase\">Exemple<\/h3>\n\n<div class=\"acf-innerblocks-container\">\r\n\r\n<p>Votre enfant est en 6e ann\u00e9e et son \u00e9cole actuelle n&#8217;offre pas de cours \u00e0 partir de la 7e ann\u00e9e. Vous devez d\u00e9cider de l&#8217;\u00e9cole qu&#8217;il fr\u00e9quentera en 7e ann\u00e9e. Deux options s&#8217;offrent \u00e0 vous : un coll\u00e8ge qui n&#8217;accueille que les \u00e9l\u00e8ves de la 7e \u00e0 la 9e ann\u00e9e ou un lyc\u00e9e qui accueille les \u00e9l\u00e8ves de la 7e \u00e0 la 12e ann\u00e9e. Certains des amis les plus proches de votre enfant iront au coll\u00e8ge, mais le lyc\u00e9e propose un programme r\u00e9put\u00e9 qui int\u00e9resse votre enfant.   <\/p>\r\n\r\n\r\n\r\n<p>Quelques mois avant la date limite d&#8217;inscription \u00e0 l&#8217;\u00e9cole, dites \u00e0 l&#8217;autre parent que vous voulez discuter de cette question. Si vous en parlez quelques jours avant la date limite, il n&#8217;aura pas le temps d&#8217;examiner lui-m\u00eame les options et de vous communiquer sa pr\u00e9f\u00e9rence. Vous risquez \u00e9galement de ne pas respecter la date limite d&#8217;inscription et de ne plus avoir le choix.  <\/p>\r\n\r\n\r\n\r\n<p>Mettez-vous d&#8217;accord sur la mani\u00e8re et le moment d&#8217;aborder cette question.<\/p>\r\n\r\n\r\n\r\n<p>Avant la r\u00e9union, r\u00e9fl\u00e9chissez aux avantages et aux inconv\u00e9nients de chaque \u00e9cole. Pensez aux <span class=\"wp-glossary-term-ignore\">frais<\/span> de scolarit\u00e9 de votre enfant dans les deux \u00e9coles, y compris les <span class=\"wp-glossary-term-ignore\">frais<\/span> de transport. R\u00e9fl\u00e9chissez \u00e0 la mani\u00e8re dont la scolarisation de votre enfant dans chaque \u00e9cole peut avoir une incidence sur le plan parental. N&#8217;oubliez pas de r\u00e9fl\u00e9chir \u00e0 ce qui est le <a href=\"https:\/\/family.cplea.ca\/fr\/article\/le-principe-de-linteret-superieur-de-lenfant\/\">meilleur pour votre enfant<\/a> pas vous.<\/p>\r\n\r\n\r\n\r\n<p>Lorsque vous discutez du probl\u00e8me avec l&#8217;autre parent, restez concentr\u00e9. Ne commencez pas \u00e0 soulever d&#8217;autres questions. Si vous devez aborder d&#8217;autres questions, faites-en la liste et fixez un moment o\u00f9 vous pourrez les aborder plus tard. Travaillez ensemble avec l&#8217;objectif commun de d\u00e9terminer quelle \u00e9cole est la meilleure option pour votre enfant.   <\/p>\r\n\r\n\r\n\r\n<p>Une fois que vous avez pris une d\u00e9cision, mettez-la par \u00e9crit. Il peut s&#8217;agir simplement de l&#8217;envoi par l&#8217;un d&#8217;entre vous d&#8217;un texte ou d&#8217;un courriel \u00e0 l&#8217;autre parent pour confirmer la d\u00e9cision. D\u00e9terminez qui doit faire quoi pour inscrire votre enfant et si votre <a href=\"https:\/\/family.cplea.ca\/fr\/article\/elaborez-un-plan-sur-la-facon-de-devenir-coparents\/\">plan parental<\/a> doit changer.<\/p>\r\n\r\n<\/div>\n<\/div>\n\r\n\r\n\n<div class=\"wp-block-group has-border-color block--callout is-style-info has-global-padding is-layout-constrained wp-container-core-group-is-layout-e555385e wp-block-group-is-layout-constrained\" style=\"border-color:#3F3F41;border-width:1px;border-radius:5px\">\n<div class=\"wp-block-group has-background block--callout-header has-global-padding is-layout-constrained wp-container-core-group-is-layout-54baa1d7 wp-block-group-is-layout-constrained\" style=\"border-bottom-color:var(--wp--preset--color--contrast);border-bottom-width:1px;padding-top:0.5em;padding-right:var(--wp--preset--spacing--30);padding-bottom:0.5em;padding-left:var(--wp--preset--spacing--30)\">\n\n<h3 class=\"wp-block-heading\">Apprendre \u00e0 co-parenter apr\u00e8s une s\u00e9paration<\/h3>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-container-core-group-is-layout-a35945ca wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--30);padding-right:var(--wp--preset--spacing--30);padding-bottom:var(--wp--preset--spacing--30);padding-left:var(--wp--preset--spacing--30)\"><div class=\"stack\">\r\n\r\n<p><a href=\"https:\/\/pas.albertacourts.ab.ca\/\"><strong>Le r\u00f4le parental apr\u00e8s la s\u00e9paration (PAS)<\/strong><\/a> est un cours en ligne gratuit cr\u00e9\u00e9 par le gouvernement de l&#8217;Alberta pour aider les parents \u00e0 apprendre \u00e0 communiquer entre eux apr\u00e8s une s\u00e9paration. Le tribunal encourage tous les parents \u00e0 suivre ce cours, m\u00eame s&#8217;il ne l&#8217;ordonne pas.<\/p>\r\n\r\n\r\n\r\n<p>Une fois que vous avez termin\u00e9 le PAS, vous pouvez suivre un deuxi\u00e8me cours appel\u00e9 <a href=\"https:\/\/pas.albertacourts.ab.ca\/\">Le r\u00f4le parental apr\u00e8s la s\u00e9paration pour les familles en situation de conflit grave<\/a>.<\/p>\r\n\r\n\r\n\r\n<p>L\u2019<a href=\"https:\/\/www.albertafamilywellness.org\/brain-story-certification-french\/\">Initiative pour le bien-\u00eatre des familles de l&#8217;Alberta<\/a> dispose d&#8217;une <strong>Cours intitul\u00e9 Histoire<\/strong> du cerveau que les parents et les professionnels peuvent suivre pour mieux comprendre le cerveau et les traumatismes de l&#8217;enfant. Il explique \u00e9galement comment les comportements et les d\u00e9cisions des parents influent sur leurs enfants.<\/p>\r\n\r\n<\/div><\/div>\n<\/div>\n\r\n\r\n\n<div class=\"wp-block-group is-style-potential-issues is-layout-flow wp-block-group-is-layout-flow\" style=\"padding-top:var(--wp--preset--spacing--30);padding-bottom:0\">\n<h2 class=\"wp-block-heading\" id=\"potential-issues\">Probl\u00e8mes potentiels<\/h2>\n\n<div class=\"acf-innerblocks-container\">\r\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"acf-innerblocks-container\">\r\n\r\n<p><strong>Vous et l\u2019autre personne n\u2019arrivez pas \u00e0 vous mettre d\u2019accord.<\/strong><\/p>\r\n\r\n\r\n\r\n<p>Il se peut que vous deviez&nbsp;<a href=\"https:\/\/family.cplea.ca\/fr\/article\/moyens-de-resoudre-les-differends\/\">obtenir l\u2019aide d\u2019un professionnel<\/a>&nbsp;ou demander \u00e0 la cour de&nbsp;<a href=\"https:\/\/family.cplea.ca\/fr\/article\/obtenir-ou-repondre-a-une-ordonnance-du-tribunal\/\">passer ou modifier une ordonnance<\/a>&nbsp;pour r\u00e9soudre le probl\u00e8me.<\/p>\r\n\r\n<\/div>\n<\/div>\n\r\n\r\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"acf-innerblocks-container\">\r\n\r\n<p><strong>Une personne ne respecte pas l\u2019accord ou l\u2019ordonnance du tribunal.<\/strong><\/p>\r\n\r\n\r\n\r\n<p>Si vous avez conclu un accord, vous pouvez demander \u00e0 l\u2019autre personne si elle est d\u2019accord pour en faire une&nbsp;<a href=\"https:\/\/family.cplea.ca\/fr\/article\/rendre-une-ordonnance-par-consentement\/\">ordonnance de consentement<\/a>. Il s\u2019agit d\u2019une ordonnance que le tribunal peut faire appliquer si quelqu\u2019un ne la respecte pas. Si vous disposez d\u2019une ordonnance, examinez-la pour voir ce qu\u2019elle pr\u00e9voit de faire si une personne ne la respecte pas.<\/p>\r\n\r\n<\/div>\n<\/div>\n\r\n\r\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"acf-innerblocks-container\">\r\n\r\n<p><strong>L\u2019autre personne est harcelante ou agressive lorsqu\u2019elle communique.<\/strong><\/p>\r\n\r\n\r\n\r\n<p>Si vous ne vous sentez pas en s\u00e9curit\u00e9 ou \u00e0 l\u2019aise pour communiquer avec l\u2019autre personne, vous pouvez demander au tribunal une&nbsp;<a href=\"https:\/\/family.cplea.ca\/fr\/article\/que-faire-en-cas-de-violence-familiale\/#types-dordonnances-de-protection\">ordonnance de protection<\/a>&nbsp;qui limite la mani\u00e8re et le moment o\u00f9 l\u2019autre personne vous contacte.<\/p>\r\n\r\n<\/div>\n<\/div>\n\r\n\r\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"acf-innerblocks-container\">\r\n\r\n<p><strong>Vous devez obtenir le consentement de l\u2019autre parent, mais il refuse de communiquer avec vous.<\/strong><\/p>\r\n\r\n\r\n\r\n<p>Les&nbsp;<a href=\"https:\/\/family.cplea.ca\/fr\/article\/etre-parent-ou-tuteur\/\">parents et tuteurs<\/a> doivent prendre les d\u00e9cisions ensemble, \u00e0 moins qu\u2019une ordonnance du tribunal n\u2019en dispose autrement. Si l\u2019autre parent ne r\u00e9pond pas \u00e0 vos demandes, vous pouvez&nbsp;<a href=\"https:\/\/family.cplea.ca\/fr\/article\/obtenir-ou-repondre-a-une-ordonnance-du-tribunal\/\">demander au tribunal de rendre une ordonnance<\/a>&nbsp;pour retirer leur consentement pour toutes ou certaines d\u00e9cisions concernant votre enfant.<\/p>\r\n\r\n<\/div>\n<\/div>\n\r\n<\/div>\n<\/div>\n<!-- \/wp:group --><\/div>\r\n\r\n\r\n\r\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\">\n<div class=\"wp-block-group is-style-sidebar is-sticky is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-exit\"><a class=\"wp-block-button__link wp-element-button\">Sortie s\u00e9curis\u00e9e\n<\/a><\/div>\n<\/div>\n\n<h2 class=\"wp-block-heading on-this-page\">Sur cette page<\/h2>\n<ul class=\"toc\"><\/ul>\n\n<h2 class=\"wp-block-heading\">D\u00e9tails<\/h2>\n<h3>Reviewed<\/h3><div class=\"wp-block-post-date__modified-date wp-block-post-date\"><time>13 June, 2024<\/time><\/div><h3>Sujets<\/h3><div class=\"taxonomy-topic wp-block-post-terms\"><a href=\"https:\/\/family.cplea.ca\/fr\/topic\/couples-fr\/\" rel=\"tag\">Couples<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/family.cplea.ca\/fr\/topic\/leducation-des-enfants-apres-la-separation\/\" rel=\"tag\">L&#8217;\u00e9ducation des enfants apr\u00e8s la s\u00e9paration<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/family.cplea.ca\/fr\/topic\/mariage\/\" rel=\"tag\">Mariage<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/family.cplea.ca\/fr\/topic\/resolution-des-litiges\/\" rel=\"tag\">R\u00e9solution des litiges<\/a><\/div>\n<h2 class=\"wp-block-heading\">Partager cette page<\/h2>\n\n<\/div>\n<\/div>\r\n<\/div>\r\n\r\n\r\n\n<div class=\"wp-block-group block--article-cards is-layout-flow wp-block-group-is-layout-flow\">\n\n<h3 class=\"wp-block-heading\">Explorer les sujets connexes<\/h3>\n<section class=\"block block--articles grid\"><article id=\"post-1939\" class=\"block--card card--article four six_t twelve_m type--action\"><div class=\"block--content stack\">\n\t\t\t\t\t<h3 class=\"wp-block-heading\" id=\"concluez-un-accord-de-separation\">Concluez un accord de s\u00e9paration<\/h3>\n\t\t\t\t\t<p>Marche \u00e0 suivre pour conclure un accord juridique apr\u00e8s une s\u00e9paration.<\/p>\n\t\t\t\t<div class=\"wp-block-buttons is-content-justification-right is-layout-flex wp-container-core-buttons-is-layout-d445cf74 wp-block-buttons-is-layout-flex\">\n\t\t\t\t<div class=\"wp-block-button is-style-arrow breakout-button\"><a href=\"https:\/\/family.cplea.ca\/fr\/article\/conclure-un-accord-de-separation\/\" class=\"wp-block-button__link wp-element-button\">Read more<\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/article><article id=\"post-1932\" class=\"block--card card--article four six_t twelve_m type--action\"><div class=\"block--content stack\">\n\t\t\t\t\t<h3 class=\"wp-block-heading\" id=\"elaborez-un-plan-sur-la-facon-de-devenir-coparents\">\u00c9laborez un plan sur la fa\u00e7on de devenir coparents<\/h3>\n\t\t\t\t\t<p>Planifiez la fa\u00e7on dont vous allez co-\u00e9lever votre enfant apr\u00e8s une s\u00e9paration.<\/p>\n\t\t\t\t<div class=\"wp-block-buttons is-content-justification-right is-layout-flex wp-container-core-buttons-is-layout-d445cf74 wp-block-buttons-is-layout-flex\">\n\t\t\t\t<div class=\"wp-block-button is-style-arrow breakout-button\"><a href=\"https:\/\/family.cplea.ca\/fr\/article\/elaborez-un-plan-sur-la-facon-de-devenir-coparents\/\" class=\"wp-block-button__link wp-element-button\">Read more<\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/article><article id=\"post-1982\" class=\"block--card card--article four six_t twelve_m type--action\"><div class=\"block--content stack\">\n\t\t\t\t\t<h3 class=\"wp-block-heading\" id=\"rendre-une-ordonnance-par-consentement\">Rendre une ordonnance par consentement<\/h3>\n\t\t\t\t\t<p>Comment pr\u00e9parer et demander au tribunal une ordonnance par consentement.<\/p>\n\t\t\t\t<div class=\"wp-block-buttons is-content-justification-right is-layout-flex wp-container-core-buttons-is-layout-d445cf74 wp-block-buttons-is-layout-flex\">\n\t\t\t\t<div class=\"wp-block-button is-style-arrow breakout-button\"><a href=\"https:\/\/family.cplea.ca\/fr\/article\/rendre-une-ordonnance-par-consentement\/\" class=\"wp-block-button__link wp-element-button\">Read more<\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/article><article id=\"post-1961\" class=\"block--card card--article four six_t twelve_m type--action\"><div class=\"block--content stack\">\n\t\t\t\t\t<h3 class=\"wp-block-heading\" id=\"moyens-de-resoudre-les-differends\">Moyens de r\u00e9soudre les diff\u00e9rends<\/h3>\n\t\t\t\t\t<p>Diff\u00e9rentes options, y compris des professionnels qui peuvent vous aider.<\/p>\n\t\t\t\t<div class=\"wp-block-buttons is-content-justification-right is-layout-flex wp-container-core-buttons-is-layout-d445cf74 wp-block-buttons-is-layout-flex\">\n\t\t\t\t<div class=\"wp-block-button is-style-arrow breakout-button\"><a href=\"https:\/\/family.cplea.ca\/fr\/article\/moyens-de-resoudre-les-differends\/\" class=\"wp-block-button__link wp-element-button\">Read more<\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/article><article id=\"post-1976\" class=\"block--card card--article four six_t twelve_m type--action\"><div class=\"block--content stack\">\n\t\t\t\t\t<h3 class=\"wp-block-heading\" id=\"obtenir-ou-repondre-a-une-ordonnance-du-tribunal\">Obtenir ou r\u00e9pondre \u00e0 une ordonnance du tribunal<\/h3>\n\t\t\t\t\t<p>Demander au tribunal une ordonnance pour r\u00e9soudre les probl\u00e8mes familiaux.<\/p>\n\t\t\t\t<div class=\"wp-block-buttons is-content-justification-right is-layout-flex wp-container-core-buttons-is-layout-d445cf74 wp-block-buttons-is-layout-flex\">\n\t\t\t\t<div class=\"wp-block-button is-style-arrow breakout-button\"><a href=\"https:\/\/family.cplea.ca\/fr\/article\/obtenir-ou-repondre-a-une-ordonnance-du-tribunal\/\" class=\"wp-block-button__link wp-element-button\">Read more<\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/article><\/section><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Conseils pour une communication efficace apr\u00e8s une s\u00e9paration.<\/p>\n","protected":false},"featured_media":1832,"template":"","meta":{"_acf_changed":true,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":""},"topic":[122,127,175,132],"article-type":[168],"class_list":["post-1962","article","type-article","status-publish","has-post-thumbnail","hentry","topic-couples-fr","topic-leducation-des-enfants-apres-la-separation","topic-mariage","topic-resolution-des-litiges","article-type-approfondir"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comment communiquer avec l&#039;autre personne - CPLEA Family Law<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/family.cplea.ca\/fr\/article\/comment-communiquer-avec-lautre-personne\/\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/article\\\/comment-communiquer-avec-lautre-personne\\\/\",\"url\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/article\\\/comment-communiquer-avec-lautre-personne\\\/\",\"name\":\"Comment communiquer avec l'autre personne - CPLEA Family Law\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/article\\\/comment-communiquer-avec-lautre-personne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/article\\\/comment-communiquer-avec-lautre-personne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/family.cplea.ca\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/getting-help.png\",\"datePublished\":\"2024-01-22T20:27:17+00:00\",\"dateModified\":\"2025-08-27T19:10:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/article\\\/comment-communiquer-avec-lautre-personne\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/article\\\/comment-communiquer-avec-lautre-personne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/article\\\/comment-communiquer-avec-lautre-personne\\\/#primaryimage\",\"url\":\"https:\\\/\\\/family.cplea.ca\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/getting-help.png\",\"contentUrl\":\"https:\\\/\\\/family.cplea.ca\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/getting-help.png\",\"width\":391,\"height\":323},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/article\\\/comment-communiquer-avec-lautre-personne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment communiquer avec l&#8217;autre personne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/\",\"name\":\"CPLEA Family Law\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/#organization\",\"name\":\"CPLEA Family Law\",\"url\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/family.cplea.ca\\\/wp-content\\\/uploads\\\/CPLEA-new-web-logo-FR-1-1.png\",\"contentUrl\":\"https:\\\/\\\/family.cplea.ca\\\/wp-content\\\/uploads\\\/CPLEA-new-web-logo-FR-1-1.png\",\"width\":1784,\"height\":273,\"caption\":\"CPLEA Family Law\"},\"image\":{\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CPLEAlberta\",\"https:\\\/\\\/x.com\\\/cplealberta\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment communiquer avec l'autre personne - CPLEA Family Law","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/family.cplea.ca\/fr\/article\/comment-communiquer-avec-lautre-personne\/","twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/family.cplea.ca\/fr\/article\/comment-communiquer-avec-lautre-personne\/","url":"https:\/\/family.cplea.ca\/fr\/article\/comment-communiquer-avec-lautre-personne\/","name":"Comment communiquer avec l'autre personne - CPLEA Family Law","isPartOf":{"@id":"https:\/\/family.cplea.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/family.cplea.ca\/fr\/article\/comment-communiquer-avec-lautre-personne\/#primaryimage"},"image":{"@id":"https:\/\/family.cplea.ca\/fr\/article\/comment-communiquer-avec-lautre-personne\/#primaryimage"},"thumbnailUrl":"https:\/\/family.cplea.ca\/wp-content\/uploads\/2024\/01\/getting-help.png","datePublished":"2024-01-22T20:27:17+00:00","dateModified":"2025-08-27T19:10:08+00:00","breadcrumb":{"@id":"https:\/\/family.cplea.ca\/fr\/article\/comment-communiquer-avec-lautre-personne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/family.cplea.ca\/fr\/article\/comment-communiquer-avec-lautre-personne\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/family.cplea.ca\/fr\/article\/comment-communiquer-avec-lautre-personne\/#primaryimage","url":"https:\/\/family.cplea.ca\/wp-content\/uploads\/2024\/01\/getting-help.png","contentUrl":"https:\/\/family.cplea.ca\/wp-content\/uploads\/2024\/01\/getting-help.png","width":391,"height":323},{"@type":"BreadcrumbList","@id":"https:\/\/family.cplea.ca\/fr\/article\/comment-communiquer-avec-lautre-personne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/family.cplea.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Comment communiquer avec l&#8217;autre personne"}]},{"@type":"WebSite","@id":"https:\/\/family.cplea.ca\/fr\/#website","url":"https:\/\/family.cplea.ca\/fr\/","name":"CPLEA Family Law","description":"","publisher":{"@id":"https:\/\/family.cplea.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/family.cplea.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/family.cplea.ca\/fr\/#organization","name":"CPLEA Family Law","url":"https:\/\/family.cplea.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/family.cplea.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/family.cplea.ca\/wp-content\/uploads\/CPLEA-new-web-logo-FR-1-1.png","contentUrl":"https:\/\/family.cplea.ca\/wp-content\/uploads\/CPLEA-new-web-logo-FR-1-1.png","width":1784,"height":273,"caption":"CPLEA Family Law"},"image":{"@id":"https:\/\/family.cplea.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CPLEAlberta","https:\/\/x.com\/cplealberta"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/family.cplea.ca\/fr\/wp-json\/wp\/v2\/article\/1962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/family.cplea.ca\/fr\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/family.cplea.ca\/fr\/wp-json\/wp\/v2\/types\/article"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/family.cplea.ca\/fr\/wp-json\/wp\/v2\/media\/1832"}],"wp:attachment":[{"href":"https:\/\/family.cplea.ca\/fr\/wp-json\/wp\/v2\/media?parent=1962"}],"wp:term":[{"taxonomy":"topic","embeddable":true,"href":"https:\/\/family.cplea.ca\/fr\/wp-json\/wp\/v2\/topic?post=1962"},{"taxonomy":"article-type","embeddable":true,"href":"https:\/\/family.cplea.ca\/fr\/wp-json\/wp\/v2\/article-type?post=1962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}