{"id":1942,"date":"2023-10-23T12:20:28","date_gmt":"2023-10-23T18:20:28","guid":{"rendered":"https:\/\/wpml.cplea.ca\/article\/ce-quil-advient-de-votre-logement\/"},"modified":"2026-01-06T11:30:21","modified_gmt":"2026-01-06T18:30:21","slug":"quarrive-t-il-a-votre-maison","status":"publish","type":"article","link":"https:\/\/family.cplea.ca\/fr\/article\/quarrive-t-il-a-votre-maison\/","title":{"rendered":"Qu&#8217;arrive-t-il \u00e0 votre maison"},"content":{"rendered":"\n<div class=\"wp-block-group is-style-lead has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<p>Le foyer familial est l&#8217;endroit o\u00f9 les \u00e9poux\/partenaires ont v\u00e9cu pendant qu&#8217;ils \u00e9taient ensemble. L&#8217;un d&#8217;entre vous ou les deux peuvent \u00eatre propri\u00e9taires ou locataires du logement familial. La question de savoir qui habite le logement familial apr\u00e8s la s\u00e9paration et ce qu&#8217;il convient d&#8217;en faire \u00e0 long terme est souvent un sujet de d\u00e9saccord.  <\/p>\n\n\n\n<p>Les informations contenues dans cette page s&#8217;appliquent uniquement aux conjoints et aux partenaires. La <a href=\"https:\/\/family.cplea.ca\/fr\/article\/regles-de-repartition\/\" data-type=\"\" data-id=\"\">loi est diff\u00e9rente pour les couples non mari\u00e9s<\/a> qui ne sont pas des partenaires adultes interd\u00e9pendants. <\/p>\n\n\n\n<p class=\"is-style-on-this-page\">Dans cette page, le terme &#8220;partenaire&#8221; fait r\u00e9f\u00e9rence \u00e0 un <a href=\"https:\/\/family.cplea.ca\/fr\/article\/quel-est-votre-etat-civil\/\" data-type=\"article\" data-id=\"418\">partenaire adulte interd\u00e9pendant<\/a>.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-style-mobile-jumplinks is-style-sidebar ghostkit-d-none ghostkit-d-xl-none ghostkit-d-lg-none ghostkit-d-md-none ghostkit-d-sm-block has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading on-this-page\">Sur cette page<\/h2>\n<ul class=\"toc\"><\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:75%\" id=\"content\">\n<div class=\"wp-block-group is-style-summary is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\" id=\"need-to-know\">Besoin de savoir<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Si vous et votre conjoint\/partenaire \u00eates d&#8217;accord sur ce qu&#8217;il convient de faire de la maison, vous pouvez inclure ces d\u00e9tails dans votre <a href=\"https:\/\/family.cplea.ca\/fr\/article\/conclure-un-accord-de-separation\/\" data-type=\"article\" data-id=\"439\">accord de s\u00e9paration<\/a>.<\/li>\n\n\n\n<li>Si vous ne parvenez pas \u00e0 vous mettre d&#8217;accord sur ce qu&#8217;il convient de faire de la maison, il est possible de faire appel \u00e0 un <a href=\"https:\/\/family.cplea.ca\/article\/ways-to-resolve-disputes\/\" data-type=\"article\" data-id=\"454\">professionnel<\/a> ou le <a href=\"https:\/\/family.cplea.ca\/article\/when-you-cant-agree-how-to-divide-your-assets-and-debts\/\" data-type=\"article\" data-id=\"340\">tribunal<\/a> peut aider.<\/li>\n\n\n\n<li>Une ordonnance de possession exclusive peut permettre \u00e0 une personne de rester dans le domicile familial pendant un certain temps et ordonner \u00e0 l&#8217;autre personne de d\u00e9m\u00e9nager.<\/li>\n\n\n\n<li>Si une personne vit dans le logement mais ne coop\u00e8re pas pour le g\u00e9rer, le tribunal peut prendre des d\u00e9cisions.<\/li>\n<\/ul>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"get-started\">Pour commencer<\/h2>\n\n\n\n<p class=\"is-style-learn-the-basics\">Apprenez la base des <a href=\"https:\/\/family.cplea.ca\/fr\/article\/regles-pour-tout-repartir\/\" data-type=\"article\" data-id=\"322\">r\u00e8gles pour tout r\u00e9partir<\/a> avant de vous occuper de votre maison familiale. <\/p>\n\n\n\n<p>Ensuite, vous devez rassembler des informations sur votre maison familiale.<\/p>\n\n\n\n<h3 class=\"wp-block-heading is-style-highlighted\" id=\"if-you-rent-your-home\">Si vous louez votre logement<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>les noms figurant sur le bail<\/li>\n\n\n\n<li>la date de renouvellement ou de fin du bail<\/li>\n\n\n\n<li>la proc\u00e9dure de r\u00e9siliation anticip\u00e9e du bail<\/li>\n\n\n\n<li>le montant du loyer, sa date de paiement et la personne qui le paie<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading is-style-highlighted\" id=\"if-you-own-your-home\">Si vous \u00eates propri\u00e9taire de votre logement<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>les noms inscrits sur le titre de propri\u00e9t\u00e9 et, si plusieurs personnes sont inscrites, s&#8217;il s&#8217;agit de locataires conjoints ou de locataires en commun<\/li>\n\n\n\n<li>si le domicile est couvert par une hypoth\u00e8que et, dans l&#8217;affirmative, quel montant a \u00e9t\u00e9 pay\u00e9 et quel montant est encore d\u00fb<\/li>\n\n\n\n<li>qui a contribu\u00e9 \u00e0 l&#8217;acquisition du domicile, par exemple qui a vers\u00e9 la mise de fonds ou si vous avez re\u00e7u un don de la part de quelqu&#8217;un d&#8217;autre<\/li>\n\n\n\n<li>la valeur marchande du logement<\/li>\n<\/ul>\n\n\n\n<p>Si l&#8217;un d&#8217;entre vous ou les deux ont h\u00e9rit\u00e9 de la maison familiale, visitez la page <a href=\"https:\/\/family.cplea.ca\/article\/what-happens-to-an-inheritance\/\" data-type=\"article\" data-id=\"337\">Qu&#8217;arrive-t-il \u00e0 un h\u00e9ritage<\/a> pour en savoir plus.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"figure-out-short-term-living-arrangements\">Trouver des solutions de logement \u00e0 court terme<\/h2>\n\n\n\n<p>Ce que vous d\u00e9cidez de faire \u00e0 court terme ne doit pas n\u00e9cessairement \u00eatre la m\u00eame chose que la fa\u00e7on dont vous acceptez de g\u00e9rer le foyer familial \u00e0 long terme.<\/p>\n\n\n\n<p>Une fois que vous vous \u00eates s\u00e9par\u00e9s, vous pouvez ou non continuer \u00e0 vivre ensemble dans la m\u00eame maison. Peut-\u00eatre que l&#8217;un d&#8217;entre vous d\u00e9m\u00e9nagera et que l&#8217;autre restera dans le domicile. Peut-\u00eatre resterez-vous tous les deux dans le foyer mais aurez des vies s\u00e9par\u00e9es. Si vous avez des enfants, ils resteront peut-\u00eatre \u00e0 plein temps dans le logement tandis que chacun d&#8217;entre vous y vivra \u00e0 tour de r\u00f4le avec eux, ce que l&#8217;on appelle la nidification (nesting). Il se peut aussi que vous souhaitiez tous les deux d\u00e9m\u00e9nager.    <\/p>\n\n\n\n<p>Si vous avez des enfants, vos conditions de vie doivent correspondre \u00e0 leurs <a data-type=\"article\" data-id=\"429\" href=\"https:\/\/family.cplea.ca\/fr\/article\/le-principe-de-linteret-superieur-de-lenfant\/\">int\u00e9r\u00eats sup\u00e9rieurs<\/a>. R\u00e9fl\u00e9chissez aux conditions de vie qui les affecteront le moins. Vos conditions de vie auront \u00e9galement un impact sur le <a data-type=\"article\" data-id=\"431\" href=\"https:\/\/family.cplea.ca\/fr\/article\/elaborez-un-plan-sur-la-facon-de-devenir-coparents\/\">plan parental<\/a>.<\/p>\n\n\n\n<p>Si vous ne parvenez pas \u00e0 vous mettre d&#8217;accord sur un mode de vie, vous pouvez demander au tribunal de rendre une ordonnance vous accordant la possession exclusive du domicile familial. Vous pouvez obtenir une ordonnance pour un logement que vous louez ou dont vous \u00eates propri\u00e9taire. Cette ordonnance vous donne le droit de vivre dans le logement pendant un certain temps. L&#8217;autre personne doit d\u00e9m\u00e9nager.   <\/p>\n\n\n\n<div class=\"wp-block-group has-border-color block--callout is-style-star has-global-padding is-layout-constrained wp-container-core-group-is-layout-e555385e wp-block-group-is-layout-constrained\" style=\"border-color:#3F3F41;border-width:1px;border-radius:5px\">\n<div class=\"wp-block-group has-background block--callout-header has-global-padding is-layout-constrained wp-container-core-group-is-layout-54baa1d7 wp-block-group-is-layout-constrained\" style=\"border-bottom-color:var(--wp--preset--color--contrast);border-bottom-width:1px;padding-top:0.5em;padding-right:var(--wp--preset--spacing--30);padding-bottom:0.5em;padding-left:var(--wp--preset--spacing--30)\">\n\n<h3 class=\"wp-block-heading\">Si vous vivez dans le m\u00eame domicile alors que vous \u00eates s\u00e9par\u00e9s<\/h3>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-container-core-group-is-layout-a35945ca wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--30);padding-right:var(--wp--preset--spacing--30);padding-bottom:var(--wp--preset--spacing--30);padding-left:var(--wp--preset--spacing--30)\"><div class=\"stack\">\n\n<p>Pour divorcer, vous devez g\u00e9n\u00e9ralement vivre s\u00e9par\u00e9ment pendant au moins un an. Vous pouvez vivre sous le m\u00eame toit tout en \u00e9tant s\u00e9par\u00e9s. <\/p>\n\n\n\n<p>Vous et votre conjoint\/partenaire vivez s\u00e9par\u00e9ment si vous :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>communiquez rarement entre vous<\/li>\n\n\n\n<li>avez des chambres s\u00e9par\u00e9es<\/li>\n\n\n\n<li>n&#8217;avez pas de relations sexuelles entre vous<\/li>\n\n\n\n<li>ne vous entraidez pas pour les t\u00e2ches m\u00e9nag\u00e8res<\/li>\n\n\n\n<li>ne faites pas d&#8217;activit\u00e9s ensemble<\/li>\n<\/ul>\n\n<\/div><\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading is-style-highlighted\" id=\"exclusive-possession-orders\">Ordonnances de possession exclusive<\/h3>\n\n\n\n<p>Une ordonnance de possession exclusive est une ordonnance du tribunal qui autorise l&#8217;un des \u00e9poux\/partenaires \u00e0 vivre dans la maison familiale et ordonne \u00e0 l&#8217;autre personne de d\u00e9m\u00e9nager. L&#8217;ordonnance peut porter sur les biens m\u00e9nagers et les v\u00e9hicules. <\/p>\n\n\n\n<p>Cette question se pose souvent lorsque les conjoints\/partenaires ont des enfants et que l&#8217;un des parents souhaite rester au domicile avec les enfants afin de r\u00e9duire l&#8217;impact de la s\u00e9paration sur eux.<\/p>\n\n\n\n<p>Vous pouvez obtenir une ordonnance de possession exclusive pour un logement que vous poss\u00e9dez ou que vous louez. Vous pouvez obtenir une ordonnance de possession exclusive m\u00eame si votre nom ne figure pas sur le titre de propri\u00e9t\u00e9 ou le bail. <\/p>\n\n\n\n<p>Vous devez demander une ordonnance de possession exclusive \u00e0 la Cour du Banc du Roi. Si vous vous \u00eates seulement adress\u00e9 \u00e0 la Cour de <span class=\"wp-glossary-term-ignore\">justice <\/span>que pour r\u00e9gler d&#8217;autres questions li\u00e9es \u00e0 la s\u00e9paration, vous devez ouvrir un nouveau dossier aupr\u00e8s de la Cour du Banc du Roi pour demander une ordonnance de possession exclusive.<\/p>\n\n\n\n<p>Lorsqu&#8217;il d\u00e9cide d&#8217;ordonner la possession exclusive du logement familial, le tribunal prend en compte les \u00e9l\u00e9ments suivants :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Existe-t-il d&#8217;autres lieux de vie abordables pour l&#8217;un des conjoints\/partenaires ?<\/li>\n\n\n\n<li>Si les conjoints\/partenaires louent le logement familial, le contrat de bail pr\u00e9voit-il des restrictions ou des conditions ?<\/li>\n\n\n\n<li>Qui est susceptible d&#8217;obtenir le logement familial \u00e0 long terme ? Le logement familial est-il un <a href=\"https:\/\/family.cplea.ca\/fr\/article\/regles-pour-tout-repartir\/#categories-de-biens-relevant-de-Family-Property-Act\">bien exclu<\/a> ?<\/li>\n\n\n\n<li>Quels sont les besoins des enfants vivant dans le foyer familial ? Quels seront les <a href=\"https:\/\/family.cplea.ca\/fr\/article\/regles-pour-tout-repartir\/#categories-de-biens-relevant-de-Family-Property-Act\" data-type=\"\" data-id=\"\">accords parentaux<\/a> lorsque les parents ne vivront plus sous le m\u00eame toit ? <\/li>\n\n\n\n<li>Quelle est la situation financi\u00e8re de chaque conjoint\/partenaire ? Il s&#8217;agit notamment de savoir qui paie la <a data-type=\"article\" data-id=\"426\" href=\"https:\/\/family.cplea.ca\/fr\/article\/etre-parent-ou-tuteur\/#types-daccords-parentaux\">pension alimentaire pour enfants<\/a> ou la p<a data-type=\"\" data-id=\"\" href=\"\">ension alimentaire pour \u00e9poux\/partenaire<\/a>.<\/li>\n\n\n\n<li>Y a-t-il des conflits entre les \u00e9poux\/partenaires ? Et si oui, quelle en est la gravit\u00e9 ? <\/li>\n\n\n\n<li>Existe-t-il des ordonnances du tribunal concernant la pension alimentaire pour les enfants, la pension alimentaire pour les \u00e9poux\/partenaires ou le partage des biens ?<\/li>\n<\/ul>\n\n\n\n<div class=\"ghostkit-accordion ghostkit-accordion-2\">\n<div class=\"ghostkit-accordion-item\" data-accordion=\"accordion-si-vous-etes-le-demandeur\"><div class=\"ghostkit-accordion-item-heading\"><button type=\"button\" id=\"accordion-si-vous-etes-le-demandeur-button\" aria-expanded=\"false\" aria-controls=\"accordion-si-vous-etes-le-demandeur-content\"><span class=\"ghostkit-accordion-item-label\">Si vous \u00eates le demandeur<\/span><span class=\"ghostkit-accordion-item-collapse\"><svg class=\"ghostkit-svg-icon\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M9.21967 6.2197C9.51256 5.9268 9.98744 5.9268 10.2803 6.2197L15.5303 11.4697C15.8232 11.7626 15.8232 12.2374 15.5303 12.5303L10.2803 17.7803C9.98744 18.0732 9.51256 18.0732 9.21967 17.7803C8.92678 17.4874 8.92678 17.0126 9.21967 16.7197L13.9393 12L9.21967 7.2803C8.92678 6.9874 8.92678 6.5126 9.21967 6.2197Z\" fill=\"currentColor\"><\/path><\/svg><\/span><\/button><\/div><div id=\"accordion-si-vous-etes-le-demandeur-content\" class=\"ghostkit-accordion-item-content is-layout-flow wp-block-ghostkit-accordion-item-is-layout-flow\" role=\"region\" aria-labelledby=\"accordion-si-vous-etes-le-demandeur-button\">\n<p>Vous devez suivre la proc\u00e9dure indiqu\u00e9e sur la page <a href=\"\/?p=2793\">Se rendre \u00e0 la Cour du Banc du Roi<\/a>. Les instructions ci-dessous expliquent <strong>comment d\u00e9poser une demande<\/strong>, qui est l\u2019une des \u00e9tapes de la proc\u00e9dure familiale r\u00e9guli\u00e8re \u00e0 la Cour du Banc du Roi.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Compl\u00e9ter les formulaires <a href=\"https:\/\/formsmgmt.gov.ab.ca\/Public\/CTS3459FR.xdp\"><strong>Demande \u2013 Family Law Act<\/strong><\/a> et&nbsp;<strong><a href=\"https:\/\/albertacourts.ca\/kb\/areas-of-law\/family\/family-law-forms\" target=\"_blank\" rel=\"noreferrer noopener\">Statement \u2013 Exclusive Possession of Family Home \/ Household Goods<\/a><\/strong> (formulaire en anglais seulement).<\/li>\n\n\n\n<li> Faites trois copies de chaque formulaire : une pour vous, une pour le tribunal et une pour le d\u00e9fendeur.<\/li>\n\n\n\n<li>D\u00e9posez vos formulaires compl\u00e9t\u00e9s \u00e0 la Cour du Banc du Roi.\n<ul class=\"wp-block-list\">\n<li>Si vous avez d\u00e9j\u00e0 eu recours \u00e0 la Cour du Banc du Roi pour r\u00e9gler d&#8217;autres questions relatives \u00e0 la s\u00e9paration, utilisez le m\u00eame num\u00e9ro de dossier et le m\u00eame palais de justice qu&#8217;auparavant.<\/li>\n\n\n\n<li>Si vous eu recours \u00e0 la Cour de justice pour r\u00e9gler d&#8217;autres questions li\u00e9es \u00e0 la s\u00e9paration, vous devez d\u00e9poser une demande de divorce devant la <a href=\"https:\/\/albertacourts.ca\/kb\/about\/locations-and-sittings\">Cour du Banc du Roi<\/a> le plus proche de chez vous. Le greffier vous attribuera un nouveau num\u00e9ro de dossier \u00e0 la Cour du Banc du Roi. <\/li>\n\n\n\n<li>Si vous n&#8217;avez pas encore eu recours \u00e0 un tribunal pour r\u00e9gler des probl\u00e8mes de s\u00e9paration, choisissez la <a href=\"https:\/\/albertacourts.ca\/kb\/about\/locations-and-sittings\">Cour du Banc du Roi<\/a> le plus proche de chez vous. Le greffier vous attribuera un nouveau num\u00e9ro de dossier. <\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Payez les <span class=\"wp-glossary-term-ignore\">frais <\/span>de dossier ou, si vous remplissez les conditions requises, demandez une dispense des <span class=\"wp-glossary-term-ignore\">frais<\/span>. Pour en savoir plus, t\u00e9l\u00e9chargez le document de CPLEA intitul\u00e9&nbsp;<a href=\"https:\/\/www.cplea.ca\/wp-content\/uploads\/CourtFeesAndWaiversInAlberta.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Court Fees and Waivers in Alberta<\/a>&nbsp;(document en anglais seulement).<\/li>\n\n\n\n<li><a data-type=\"article\" data-id=\"468\" href=\"https:\/\/family.cplea.ca\/article\/serve-court-documents\/\">Signifiez<\/a> une copie des formulaires que vous avez d\u00e9pos\u00e9s \u00e0 l&#8217;autre personne. Remplissez et d\u00e9posez un <a href=\"https:\/\/formsmgmt.gov.ab.ca\/Public\/CTS3513.xdp\"><strong>Affidavit of Service &#8211; Applicant<\/strong><\/a> (forumularie en anglais seulement) pour prouver que vous l&#8217;avez fait avant la date de l\u2019audience.<\/li>\n\n\n\n<li>Vous recevrez des copies des documents judiciaires d\u00e9pos\u00e9s par le d\u00e9fendeur.<\/li>\n\n\n\n<li>Pr\u00e9sentez-vous \u00e0 la date pr\u00e9vue de l&#8217;audience.<\/li>\n<\/ol>\n<\/div><\/div>\n\n\n\n<div class=\"ghostkit-accordion-item\" data-accordion=\"accordion-si-vous-etes-le-defendeur\"><div class=\"ghostkit-accordion-item-heading\"><button type=\"button\" id=\"accordion-si-vous-etes-le-defendeur-button\" aria-expanded=\"false\" aria-controls=\"accordion-si-vous-etes-le-defendeur-content\"><span class=\"ghostkit-accordion-item-label\">Si vous \u00eates le d\u00e9fendeur<\/span><span class=\"ghostkit-accordion-item-collapse\"><svg class=\"ghostkit-svg-icon\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M9.21967 6.2197C9.51256 5.9268 9.98744 5.9268 10.2803 6.2197L15.5303 11.4697C15.8232 11.7626 15.8232 12.2374 15.5303 12.5303L10.2803 17.7803C9.98744 18.0732 9.51256 18.0732 9.21967 17.7803C8.92678 17.4874 8.92678 17.0126 9.21967 16.7197L13.9393 12L9.21967 7.2803C8.92678 6.9874 8.92678 6.5126 9.21967 6.2197Z\" fill=\"currentColor\"><\/path><\/svg><\/span><\/button><\/div><div id=\"accordion-si-vous-etes-le-defendeur-content\" class=\"ghostkit-accordion-item-content is-layout-flow wp-block-ghostkit-accordion-item-is-layout-flow\" role=\"region\" aria-labelledby=\"accordion-si-vous-etes-le-defendeur-button\">\n<p>Vous devez suivre la proc\u00e9dure indiqu\u00e9e sur la page <a href=\"\/?p=2793\">Se rendre \u00e0 la Cour du Banc du Roi<\/a>. Les instructions ci-dessous expliquent <strong>comment r\u00e9pondre \u00e0 une demande<\/strong>, qui est l\u2019une des \u00e9tapes de la proc\u00e9dure familiale r\u00e9guli\u00e8re \u00e0 la Cour du Banc du Roi.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Vous obtiendrez des copies des formulaires judiciaires d\u00e9pos\u00e9s par le demandeur. Ne les ignorez pas. Notez la date de l\u2019audience et ce que vous devez faire avant.  <\/li>\n\n\n\n<li>Compl\u00e9tez les formulaires <strong><a href=\"https:\/\/albertacourts.ca\/kb\/areas-of-law\/family\/family-law-forms\/french-language-family-law-forms\">R\u00e9ponse &#8211; Family Law Act<\/a><\/strong> et <a href=\"https:\/\/albertacourts.ca\/kb\/areas-of-law\/family\/family-law-forms\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Reply Statement \u2013 Exclusive Possession of Family Home \/ Household Goods<\/strong><\/a> (formularie en anglais seulement).<\/li>\n\n\n\n<li>Faites trois copies de chaque formulaire : une pour vous, une pour le tribunal et une pour le demandeur.<\/li>\n\n\n\n<li>D\u00e9posez vos formulaires au m\u00eame palais de justice et en utilisant le m\u00eame num\u00e9ro de dossier que celui figurant sur les formulaires du demandeur.<\/li>\n\n\n\n<li><a data-type=\"article\" data-id=\"468\" href=\"https:\/\/family.cplea.ca\/article\/serve-court-documents\/\">Signifiez<\/a> une copie des formulaires d\u00e9pos\u00e9s au demandeur au moins 10 jours avant la date de l&#8217;audience. Remplissez et d\u00e9posez un <a href=\"https:\/\/cfr.forms.gov.ab.ca\/Form\/CTS3514.pdf\"><\/a><strong><strong><a href=\"https:\/\/albertacourts.ca\/kb\/areas-of-law\/family\/family-law-forms\" target=\"_blank\" rel=\"noreferrer noopener\">Affidavit of Service \u2013 Respondent<\/a><\/strong><\/strong> (formulaire en anglais seulement) pour prouver que vous les avez signifi\u00e9s avant la date de l\u2019audience.<\/li>\n\n\n\n<li>Pr\u00e9sentez-vous \u00e0 la date pr\u00e9vue de l&#8217;audience.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"figure-out-long-term-arrangements\">Concevoir des accords \u00e0 long terme<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"if-you-rent-the-family-home\">Si vous louez le logement familial<\/h3>\n\n\n\n<p>Si vous et votre conjoint\/partenaire louez le logement familial, vous avez des options. Ces options s&#8217;appliquent m\u00eame si le nom d&#8217;une seule personne figure sur le bail. <\/p>\n\n\n\n<p>Pour en savoir plus sur vos droits en tant que locataire, consultez le site de CPLEA <a href=\"http:\/\/www.landlordandtenant.org\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Laws for Landlords and Tenants in Alberta<\/strong><\/a>&nbsp;(les lois pour les propri\u00e9taires et les locataires en Alberta &#8211; site en anglais seulement).<\/p>\n\n\n\n<div class=\"ghostkit-accordion ghostkit-accordion-3\">\n<div class=\"ghostkit-accordion-item\" data-accordion=\"accordion-mettre-fin-au-bail-de-maniere-anticipee\"><div class=\"ghostkit-accordion-item-heading\"><button type=\"button\" id=\"accordion-mettre-fin-au-bail-de-maniere-anticipee-button\" aria-expanded=\"false\" aria-controls=\"accordion-mettre-fin-au-bail-de-maniere-anticipee-content\"><span class=\"ghostkit-accordion-item-label\">Mettre fin au bail de mani\u00e8re anticip\u00e9e<\/span><span class=\"ghostkit-accordion-item-collapse\"><svg class=\"ghostkit-svg-icon\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M9.21967 6.2197C9.51256 5.9268 9.98744 5.9268 10.2803 6.2197L15.5303 11.4697C15.8232 11.7626 15.8232 12.2374 15.5303 12.5303L10.2803 17.7803C9.98744 18.0732 9.51256 18.0732 9.21967 17.7803C8.92678 17.4874 8.92678 17.0126 9.21967 16.7197L13.9393 12L9.21967 7.2803C8.92678 6.9874 8.92678 6.5126 9.21967 6.2197Z\" fill=\"currentColor\"><\/path><\/svg><\/span><\/button><\/div><div id=\"accordion-mettre-fin-au-bail-de-maniere-anticipee-content\" class=\"ghostkit-accordion-item-content is-layout-flow wp-block-ghostkit-accordion-item-is-layout-flow\" role=\"region\" aria-labelledby=\"accordion-mettre-fin-au-bail-de-maniere-anticipee-button\">\n<p>Vous pouvez choisir de mettre fin \u00e0 votre bail de mani\u00e8re anticip\u00e9e afin que vous puissiez tous les deux d\u00e9m\u00e9nager. Relisez votre bail pour savoir ce qu&#8217;il pr\u00e9voit \u00e0 cet effet. <\/p>\n<\/div><\/div>\n\n\n\n<div class=\"ghostkit-accordion-item\" data-accordion=\"accordion-une-personne-negocie-un-nouveau-bail\"><div class=\"ghostkit-accordion-item-heading\"><button type=\"button\" id=\"accordion-une-personne-negocie-un-nouveau-bail-button\" aria-expanded=\"false\" aria-controls=\"accordion-une-personne-negocie-un-nouveau-bail-content\"><span class=\"ghostkit-accordion-item-label\">Une personne n\u00e9gocie un nouveau bail<\/span><span class=\"ghostkit-accordion-item-collapse\"><svg class=\"ghostkit-svg-icon\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M9.21967 6.2197C9.51256 5.9268 9.98744 5.9268 10.2803 6.2197L15.5303 11.4697C15.8232 11.7626 15.8232 12.2374 15.5303 12.5303L10.2803 17.7803C9.98744 18.0732 9.51256 18.0732 9.21967 17.7803C8.92678 17.4874 8.92678 17.0126 9.21967 16.7197L13.9393 12L9.21967 7.2803C8.92678 6.9874 8.92678 6.5126 9.21967 6.2197Z\" fill=\"currentColor\"><\/path><\/svg><\/span><\/button><\/div><div id=\"accordion-une-personne-negocie-un-nouveau-bail-content\" class=\"ghostkit-accordion-item-content is-layout-flow wp-block-ghostkit-accordion-item-is-layout-flow\" role=\"region\" aria-labelledby=\"accordion-une-personne-negocie-un-nouveau-bail-button\">\n<p>Si une personne souhaite rester dans le logement, elle peut n\u00e9gocier un nouveau bail \u00e0 son nom avec le propri\u00e9taire.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"ghostkit-accordion-item\" data-accordion=\"accordion-si-vous-etes-preoccupe-par-la-violence-familiale\"><div class=\"ghostkit-accordion-item-heading\"><button type=\"button\" id=\"accordion-si-vous-etes-preoccupe-par-la-violence-familiale-button\" aria-expanded=\"false\" aria-controls=\"accordion-si-vous-etes-preoccupe-par-la-violence-familiale-content\"><span class=\"ghostkit-accordion-item-label\">Si vous \u00eates pr\u00e9occup\u00e9 par la violence familiale<\/span><span class=\"ghostkit-accordion-item-collapse\"><svg class=\"ghostkit-svg-icon\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M9.21967 6.2197C9.51256 5.9268 9.98744 5.9268 10.2803 6.2197L15.5303 11.4697C15.8232 11.7626 15.8232 12.2374 15.5303 12.5303L10.2803 17.7803C9.98744 18.0732 9.51256 18.0732 9.21967 17.7803C8.92678 17.4874 8.92678 17.0126 9.21967 16.7197L13.9393 12L9.21967 7.2803C8.92678 6.9874 8.92678 6.5126 9.21967 6.2197Z\" fill=\"currentColor\"><\/path><\/svg><\/span><\/button><\/div><div id=\"accordion-si-vous-etes-preoccupe-par-la-violence-familiale-content\" class=\"ghostkit-accordion-item-content is-layout-flow wp-block-ghostkit-accordion-item-is-layout-flow\" role=\"region\" aria-labelledby=\"accordion-si-vous-etes-preoccupe-par-la-violence-familiale-button\">\n<p>Les personnes victimes de violences domestiques peuvent prendre des mesures pour mettre fin \u00e0 leur bail de mani\u00e8re anticip\u00e9e afin de s&#8217;\u00e9loigner de la personne qui les maltraite.<\/p>\n\n\n\n<p>Pour en savoir plus, visitez le site <strong><a href=\"https:\/\/www.willownet.ca\/ending-your-rental-lease-early\/\">Willownet<\/a><\/strong> &#8211; un site web de CPLEA sur la maltraitance et la loi en Alberta, en anglais seulement.<\/p>\n<\/div><\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading is-style-highlighted\" id=\"if-you-own-the-family-home\">Si vous \u00eates propri\u00e9taire du logement familial<\/h3>\n\n\n\n<p>Si vous et votre conjoint\/partenaire \u00eates propri\u00e9taires de la maison familiale, plusieurs options s&#8217;offrent \u00e0 vous. Ces options s&#8217;appliquent m\u00eame si le titre de propri\u00e9t\u00e9 n&#8217;est d\u00e9tenu que par une seule personne et si vous avez encore un pr\u00eat hypoth\u00e9caire \u00e0 rembourser. <\/p>\n\n\n\n<div class=\"ghostkit-accordion ghostkit-accordion-3\">\n<div class=\"ghostkit-accordion-item\" data-accordion=\"accordion-une-personne-rachete-lautre\"><div class=\"ghostkit-accordion-item-heading\"><button type=\"button\" id=\"accordion-une-personne-rachete-lautre-button\" aria-expanded=\"false\" aria-controls=\"accordion-une-personne-rachete-lautre-content\"><span class=\"ghostkit-accordion-item-label\">Une personne rach\u00e8te l&#8217;autre<\/span><span class=\"ghostkit-accordion-item-collapse\"><svg class=\"ghostkit-svg-icon\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M9.21967 6.2197C9.51256 5.9268 9.98744 5.9268 10.2803 6.2197L15.5303 11.4697C15.8232 11.7626 15.8232 12.2374 15.5303 12.5303L10.2803 17.7803C9.98744 18.0732 9.51256 18.0732 9.21967 17.7803C8.92678 17.4874 8.92678 17.0126 9.21967 16.7197L13.9393 12L9.21967 7.2803C8.92678 6.9874 8.92678 6.5126 9.21967 6.2197Z\" fill=\"currentColor\"><\/path><\/svg><\/span><\/button><\/div><div id=\"accordion-une-personne-rachete-lautre-content\" class=\"ghostkit-accordion-item-content is-layout-flow wp-block-ghostkit-accordion-item-is-layout-flow\" role=\"region\" aria-labelledby=\"accordion-une-personne-rachete-lautre-button\">\n<p>Il arrive qu&#8217;une personne ait les moyens d&#8217;acheter la part de l&#8217;autre dans la maison familiale. C&#8217;est ce que l&#8217;on appelle racheter le capital d&#8217;une personne. <\/p>\n\n\n\n<p>L&#8217;acheteur n&#8217;a pas toujours besoin de disposer de liquidit\u00e9s pour ce faire. Il peut \u00eatre en mesure de r\u00e9hypoth\u00e9quer le bien \u00e0 son seul nom. Il peut alors utiliser une <span class=\"wp-glossary-term-ignore\">partie <\/span>des fonds hypoth\u00e9caires pour payer sa part \u00e0 l&#8217;autre personne.<\/p>\n\n\n\n<p>Si vous convenez qu&#8217;une personne rach\u00e8tera l&#8217;autre, l&#8217;acheteur doit s&#8217;adresser \u00e0 sa banque ou \u00e0 son courtier en pr\u00eats hypoth\u00e9caires pour savoir s&#8217;il remplit les conditions requises. Ensuite, vous devez tous les deux : <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>d\u00e9cider de la part des capitaux qui revient \u00e0 chaque personne apr\u00e8s la prise en consid\u00e9ration des <a href=\"https:\/\/family.cplea.ca\/fr\/article\/regles-pour-tout-repartir\/#categories-de-biens-relevant-de-Family-Property-Act\">biens exclus<\/a><\/li>\n\n\n\n<li>d\u00e9cider de la r\u00e9partition de la valeur nette de la propri\u00e9t\u00e9. Il s&#8217;agit de la valeur que vous poss\u00e9dez soit g\u00e9n\u00e9ralement la valeur du march\u00e9 de la maison moins le montant d\u00fb sur l&#8217;hypoth\u00e8que. <\/li>\n\n\n\n<li>se mettre d&#8217;accord sur la valeur marchande du logement. Il peut \u00eatre n\u00e9cessaire de faire appel \u00e0 un professionnel de l&#8217;immobilier pour \u00e9valuer le logement. <\/li>\n<\/ul>\n<\/div><\/div>\n\n\n\n<div class=\"ghostkit-accordion-item\" data-accordion=\"accordion-vendre-le-logement-et-partager-le-produit-de-la-vente\"><div class=\"ghostkit-accordion-item-heading\"><button type=\"button\" id=\"accordion-vendre-le-logement-et-partager-le-produit-de-la-vente-button\" aria-expanded=\"false\" aria-controls=\"accordion-vendre-le-logement-et-partager-le-produit-de-la-vente-content\"><span class=\"ghostkit-accordion-item-label\">Vendre le logement et partager le produit de la vente<\/span><span class=\"ghostkit-accordion-item-collapse\"><svg class=\"ghostkit-svg-icon\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M9.21967 6.2197C9.51256 5.9268 9.98744 5.9268 10.2803 6.2197L15.5303 11.4697C15.8232 11.7626 15.8232 12.2374 15.5303 12.5303L10.2803 17.7803C9.98744 18.0732 9.51256 18.0732 9.21967 17.7803C8.92678 17.4874 8.92678 17.0126 9.21967 16.7197L13.9393 12L9.21967 7.2803C8.92678 6.9874 8.92678 6.5126 9.21967 6.2197Z\" fill=\"currentColor\"><\/path><\/svg><\/span><\/button><\/div><div id=\"accordion-vendre-le-logement-et-partager-le-produit-de-la-vente-content\" class=\"ghostkit-accordion-item-content is-layout-flow wp-block-ghostkit-accordion-item-is-layout-flow\" role=\"region\" aria-labelledby=\"accordion-vendre-le-logement-et-partager-le-produit-de-la-vente-button\">\n<p>Vous pouvez d\u00e9cider de vendre la maison et de partager ce qui reste apr\u00e8s avoir pay\u00e9 l&#8217;hypoth\u00e8que, l&#8217;agent immobilier et l&#8217;avocat. Vous devez alors vous mettre d&#8217;accord sur : <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>la valeur marchande du logement. Vous devrez peut-\u00eatre demander \u00e0 un professionnel de l&#8217;immobilier d&#8217;\u00e9valuer le logement. <\/li>\n\n\n\n<li>l&#8217;agent immobilier auquel vous ferez appel pour vous aider \u00e0 vendre la maison<\/li>\n\n\n\n<li>les conditions de vente, y compris le prix, la date de prise de possession la plus proche et les biens que vous incluez ou non dans la vente<\/li>\n\n\n\n<li>comment r\u00e9partir l&#8217;argent restant apr\u00e8s avoir pay\u00e9 l&#8217;hypoth\u00e8que et les autres dettes garanties par le logement, c\u2019est ce qu\u2019on appelle le produit de la vente.<\/li>\n<\/ul>\n\n\n\n<p>Si vous ne parvenez pas \u00e0 vous mettre d&#8217;accord sur le partage du produit de la vente, le tribunal peut conserver l&#8217;argent jusqu&#8217;\u00e0 ce que vous <a href=\"https:\/\/family.cplea.ca\/article\/when-you-cant-agree-how-to-divide-your-assets-and-debts\/\" data-type=\"article\" data-id=\"340\">obteniez une ordonnance de partage des biens<\/a>.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"ghostkit-accordion-item\" data-accordion=\"accordion-forcer-la-vente-du-logement\"><div class=\"ghostkit-accordion-item-heading\"><button type=\"button\" id=\"accordion-forcer-la-vente-du-logement-button\" aria-expanded=\"false\" aria-controls=\"accordion-forcer-la-vente-du-logement-content\"><span class=\"ghostkit-accordion-item-label\">Forcer la vente du logement<\/span><span class=\"ghostkit-accordion-item-collapse\"><svg class=\"ghostkit-svg-icon\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M9.21967 6.2197C9.51256 5.9268 9.98744 5.9268 10.2803 6.2197L15.5303 11.4697C15.8232 11.7626 15.8232 12.2374 15.5303 12.5303L10.2803 17.7803C9.98744 18.0732 9.51256 18.0732 9.21967 17.7803C8.92678 17.4874 8.92678 17.0126 9.21967 16.7197L13.9393 12L9.21967 7.2803C8.92678 6.9874 8.92678 6.5126 9.21967 6.2197Z\" fill=\"currentColor\"><\/path><\/svg><\/span><\/button><\/div><div id=\"accordion-forcer-la-vente-du-logement-content\" class=\"ghostkit-accordion-item-content is-layout-flow wp-block-ghostkit-accordion-item-is-layout-flow\" role=\"region\" aria-labelledby=\"accordion-forcer-la-vente-du-logement-button\">\n<p>Vous devrez peut-\u00eatre demander au tribunal de forcer la vente de la maison familiale si vous en \u00eates tous deux propri\u00e9taires et que vous n&#8217;arrivez pas \u00e0 vous mettre d&#8217;accord sur la mani\u00e8re et le moment de la vendre. Il s&#8217;agit d&#8217;une ordonnance de partage et de vente en vertu le <em>Family Property Act<\/em> (la loi sur le droit de propri\u00e9t\u00e9 de l&#8217;Alberta).<\/p>\n\n\n\n<p>En fonction de la situation, le tribunal peut ordonner :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>la division physique de la terre, comme les terres agricoles<\/li>\n\n\n\n<li>la vente du bien et le partage du produit de la vente entre les \u00e9poux\/partenaires<\/li>\n\n\n\n<li>qu\u2019une personne vende son int\u00e9r\u00eat dans le bien \u00e0 l&#8217;autre personne<\/li>\n<\/ul>\n\n\n\n<p>Le tribunal peut diriger chaque \u00e9tape du processus de vente, qu&#8217;il s&#8217;agisse du choix de l&#8217;agent immobilier, du prix ou de la date \u00e0 laquelle les personnes vivant dans le logement doivent d\u00e9m\u00e9nager. Le tribunal peut \u00e9galement autoriser une seule personne \u00e0 signer les documents de vente du logement si l&#8217;autre personne refuse de coop\u00e9rer pour faire avancer la vente. <\/p>\n\n\n\n<p>Pour obtenir une ordonnance, suivez les instructions figurant sur la page <a data-type=\"article\" data-id=\"464\" href=\"https:\/\/family.cplea.ca\/article\/get-or-respond-to-a-court-order\/\">Obtenir ou r\u00e9pondre \u00e0 une ordonnance du tribunal<\/a>.<\/p>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-style-next-steps is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\" id=\"next-steps\">Prochaines \u00e9tapes<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a data-type=\"article\" data-id=\"440\" href=\"https:\/\/family.cplea.ca\/article\/share-financial-information-to-divide-assets-and-debts\/\">Partager des informations financi\u00e8res pour diviser vos actifs et vos dettes<\/a> et demander \u00e0 l&#8217;autre personne de faire de m\u00eame<\/li>\n\n\n\n<li><a data-type=\"article\" data-id=\"324\" href=\"https:\/\/family.cplea.ca\/article\/how-to-divide-assets-and-debts\/\">Diviser vos actifs et dettes<\/a> vous-m\u00eame \u00e0 la suite de la s\u00e9paration<\/li>\n\n\n\n<li><a data-type=\"article\" data-id=\"439\" href=\"https:\/\/family.cplea.ca\/fr\/article\/conclure-un-accord-de-separation\/\">Conclure un accord de s\u00e9paration<\/a> incluant la fa\u00e7on dont vous allez g\u00e9rer le foyer familial<\/li>\n\n\n\n<li><a href=\"https:\/\/family.cplea.ca\/article\/what-happens-to-an-inheritance\/\" data-type=\"article\" data-id=\"337\">D\u00e9terminer ce qu&#8217;il advient d&#8217;un h\u00e9ritage<\/a><\/li>\n\n\n\n<li><a data-type=\"article\" data-id=\"340\" href=\"https:\/\/family.cplea.ca\/article\/when-you-cant-agree-how-to-divide-your-assets-and-debts\/\">Introduire une demande<\/a> si vous ne parvenez pas \u00e0 vous mettre d&#8217;accord sur le partage de vos biens et de vos dettes<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-style-potential-issues is-layout-flow wp-block-group-is-layout-flow\" style=\"padding-top:var(--wp--preset--spacing--30);padding-bottom:0\">\n<h2 class=\"wp-block-heading\" id=\"potential-issues\">Probl\u00e8mes potentiels<\/h2>\n\n<div class=\"acf-innerblocks-container\">\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"acf-innerblocks-container\">\n\n<p><strong>Une personne ne se sent pas en s\u00e9curit\u00e9 en vivant avec l&#8217;autre, mais n&#8217;a pas assez d&#8217;argent pour d\u00e9m\u00e9nager.<\/strong><\/p>\n\n\n\n<p>Vous pouvez demander au tribunal une ordonnance de possession exclusive. Si vous louez le logement, vous pouvez peut-\u00eatre mettre fin au bail de mani\u00e8re anticip\u00e9e. Lisez ci-dessus comment obtenir une ordonnance de possession exclusive. Vous trouverez d&#8217;autres ressources sur la page <a href=\"https:\/\/family.cplea.ca\/fr\/article\/si-ut-es-en-danger\/\">Si tu es en danger<\/a>.<\/p>\n\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"acf-innerblocks-container\">\n\n<p><strong>Une personne a la possession exclusive du logement familial et n\u2019a \u00e0 effectuer que peu ou pas de paiements, tandis que l&#8217;autre personne doit payer un loyer ou une hypoth\u00e8que pour vivre ailleurs.<\/strong><\/p>\n\n\n\n<p>La personne en possession exclusive peut \u00eatre amen\u00e9e \u00e0 d\u00e9dommager l&#8217;autre personne pour les <span class=\"wp-glossary-term-ignore\">frais<\/span> de subsistance \u00e9lev\u00e9s de cette derni\u00e8re. Il s&#8217;agit du loyer d&#8217;occupation. Cette situation se produit le plus souvent lorsqu&#8217;il n&#8217;y a pas ou peu d&#8217;hypoth\u00e8que ou d&#8217;argent d\u00fb sur le logement familial. La pension alimentaire pour \u00e9poux\/partenaire peut \u00e9galement tenir compte des diff\u00e9rences de d\u00e9penses.  <\/p>\n\n<\/div>\n<\/div>\n\n<\/div>\n<\/div>\n<!-- \/wp:group --><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\">\n<div class=\"wp-block-group is-style-sidebar is-sticky is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-exit\"><a class=\"wp-block-button__link wp-element-button\">Sortie s\u00e9curis\u00e9e\n<\/a><\/div>\n<\/div>\n\n<h2 class=\"wp-block-heading on-this-page\">Sur cette page<\/h2>\n<ul class=\"toc\"><\/ul>\n\n<h2 class=\"wp-block-heading\">D\u00e9tails<\/h2>\n<h3>Reviewed<\/h3><div class=\"wp-block-post-date__modified-date wp-block-post-date\"><time>13 June, 2024<\/time><\/div><h3>Sujets<\/h3><div class=\"taxonomy-topic wp-block-post-terms\"><a href=\"https:\/\/family.cplea.ca\/fr\/topic\/biens\/\" rel=\"tag\">Biens<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/family.cplea.ca\/fr\/topic\/couples-fr\/\" rel=\"tag\">Couples<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/family.cplea.ca\/fr\/topic\/finances-fr\/\" rel=\"tag\">Finances<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/family.cplea.ca\/fr\/topic\/mariage\/\" rel=\"tag\">Mariage<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/family.cplea.ca\/fr\/topic\/marriage-fr\/\" rel=\"tag\">Marriage<\/a><\/div>\n<h2 class=\"wp-block-heading\">Partager cette page<\/h2>\n\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9terminez ce qu&#8217;il faut faire de la maison familiale apr\u00e8s une s\u00e9paration.<\/p>\n","protected":false},"featured_media":1830,"template":"","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":""},"topic":[134,122,133,175,123],"article-type":[167],"class_list":["post-1942","article","type-article","status-publish","has-post-thumbnail","hentry","topic-biens","topic-couples-fr","topic-finances-fr","topic-mariage","topic-marriage-fr","article-type-agir"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Qu&#039;arrive-t-il \u00e0 votre maison - CPLEA Family Law<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/family.cplea.ca\/fr\/article\/quarrive-t-il-a-votre-maison\/\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/article\\\/quarrive-t-il-a-votre-maison\\\/\",\"url\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/article\\\/quarrive-t-il-a-votre-maison\\\/\",\"name\":\"Qu'arrive-t-il \u00e0 votre maison - CPLEA Family Law\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/article\\\/quarrive-t-il-a-votre-maison\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/article\\\/quarrive-t-il-a-votre-maison\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/family.cplea.ca\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/ending-a-relationship.png\",\"datePublished\":\"2023-10-23T18:20:28+00:00\",\"dateModified\":\"2026-01-06T18:30:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/article\\\/quarrive-t-il-a-votre-maison\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/article\\\/quarrive-t-il-a-votre-maison\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/article\\\/quarrive-t-il-a-votre-maison\\\/#primaryimage\",\"url\":\"https:\\\/\\\/family.cplea.ca\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/ending-a-relationship.png\",\"contentUrl\":\"https:\\\/\\\/family.cplea.ca\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/ending-a-relationship.png\",\"width\":350,\"height\":478},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/article\\\/quarrive-t-il-a-votre-maison\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qu&#8217;arrive-t-il \u00e0 votre maison\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/\",\"name\":\"CPLEA Family Law\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/#organization\",\"name\":\"CPLEA Family Law\",\"url\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/family.cplea.ca\\\/wp-content\\\/uploads\\\/CPLEA-new-web-logo-FR-1-1.png\",\"contentUrl\":\"https:\\\/\\\/family.cplea.ca\\\/wp-content\\\/uploads\\\/CPLEA-new-web-logo-FR-1-1.png\",\"width\":1784,\"height\":273,\"caption\":\"CPLEA Family Law\"},\"image\":{\"@id\":\"https:\\\/\\\/family.cplea.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CPLEAlberta\",\"https:\\\/\\\/x.com\\\/cplealberta\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qu'arrive-t-il \u00e0 votre maison - CPLEA Family Law","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/family.cplea.ca\/fr\/article\/quarrive-t-il-a-votre-maison\/","twitter_misc":{"Est. reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/family.cplea.ca\/fr\/article\/quarrive-t-il-a-votre-maison\/","url":"https:\/\/family.cplea.ca\/fr\/article\/quarrive-t-il-a-votre-maison\/","name":"Qu'arrive-t-il \u00e0 votre maison - CPLEA Family Law","isPartOf":{"@id":"https:\/\/family.cplea.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/family.cplea.ca\/fr\/article\/quarrive-t-il-a-votre-maison\/#primaryimage"},"image":{"@id":"https:\/\/family.cplea.ca\/fr\/article\/quarrive-t-il-a-votre-maison\/#primaryimage"},"thumbnailUrl":"https:\/\/family.cplea.ca\/wp-content\/uploads\/2024\/01\/ending-a-relationship.png","datePublished":"2023-10-23T18:20:28+00:00","dateModified":"2026-01-06T18:30:21+00:00","breadcrumb":{"@id":"https:\/\/family.cplea.ca\/fr\/article\/quarrive-t-il-a-votre-maison\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/family.cplea.ca\/fr\/article\/quarrive-t-il-a-votre-maison\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/family.cplea.ca\/fr\/article\/quarrive-t-il-a-votre-maison\/#primaryimage","url":"https:\/\/family.cplea.ca\/wp-content\/uploads\/2024\/01\/ending-a-relationship.png","contentUrl":"https:\/\/family.cplea.ca\/wp-content\/uploads\/2024\/01\/ending-a-relationship.png","width":350,"height":478},{"@type":"BreadcrumbList","@id":"https:\/\/family.cplea.ca\/fr\/article\/quarrive-t-il-a-votre-maison\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/family.cplea.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Qu&#8217;arrive-t-il \u00e0 votre maison"}]},{"@type":"WebSite","@id":"https:\/\/family.cplea.ca\/fr\/#website","url":"https:\/\/family.cplea.ca\/fr\/","name":"CPLEA Family Law","description":"","publisher":{"@id":"https:\/\/family.cplea.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/family.cplea.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/family.cplea.ca\/fr\/#organization","name":"CPLEA Family Law","url":"https:\/\/family.cplea.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/family.cplea.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/family.cplea.ca\/wp-content\/uploads\/CPLEA-new-web-logo-FR-1-1.png","contentUrl":"https:\/\/family.cplea.ca\/wp-content\/uploads\/CPLEA-new-web-logo-FR-1-1.png","width":1784,"height":273,"caption":"CPLEA Family Law"},"image":{"@id":"https:\/\/family.cplea.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CPLEAlberta","https:\/\/x.com\/cplealberta"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/family.cplea.ca\/fr\/wp-json\/wp\/v2\/article\/1942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/family.cplea.ca\/fr\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/family.cplea.ca\/fr\/wp-json\/wp\/v2\/types\/article"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/family.cplea.ca\/fr\/wp-json\/wp\/v2\/media\/1830"}],"wp:attachment":[{"href":"https:\/\/family.cplea.ca\/fr\/wp-json\/wp\/v2\/media?parent=1942"}],"wp:term":[{"taxonomy":"topic","embeddable":true,"href":"https:\/\/family.cplea.ca\/fr\/wp-json\/wp\/v2\/topic?post=1942"},{"taxonomy":"article-type","embeddable":true,"href":"https:\/\/family.cplea.ca\/fr\/wp-json\/wp\/v2\/article-type?post=1942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}